{"id":12959,"date":"2017-03-17T14:01:50","date_gmt":"2017-03-17T17:01:50","guid":{"rendered":"https:\/\/www.tjes.jus.br\/corregedoria\/?p=12959"},"modified":"2017-03-17T14:01:50","modified_gmt":"2017-03-17T17:01:50","slug":"oficio-circular-no-772012-publ-27112012","status":"publish","type":"post","link":"https:\/\/www.tjes.jus.br\/corregedoria\/2017\/03\/17\/oficio-circular-no-772012-publ-27112012\/","title":{"rendered":"OF\u00cdCIO-CIRCULAR N\u00ba 77\/2012 &#8211; PUBL. 27\/11\/2012"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>ESTADO DO ESP\u00cdRITO SANTO<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>PODER JUDICI\u00c1RIO<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>CORREGEDORIA GERAL DA JUSTI\u00c7A<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>OF\u00cdCIO-CIRCULAR N\u00ba. 77\/2012<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Protocolo n\u00ba 201201381238<\/strong><\/p>\n<p style=\"text-align: justify;\">O Exmo. Sr. Desembargador Corregedor-Geral da Justi\u00e7a do Estado do Esp\u00edrito Santo, no uso de suas atribui\u00e7\u00f5es legais:<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong> o recebimento do Of\u00edcio Circular n\u00ba 162\/2012 &#8211; SEC da lavra do Excelent\u00edssima Desembargadora Corregedora-geral da Justi\u00e7a do Estado de Goi\u00e1s;<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong> que referido Of\u00edcio Circular informa sobre o EXTRAVIO de 50 (cinquenta) selos de Fiscaliza\u00e7\u00e3o, do Tipo: Padr\u00e3o, s\u00e9rie n\u00ba 0020BO35951 a 0020BO36000, pertencentes ao 1\u00ba Tabelionato de Notas e Registro de Im\u00f3veis da comarca de Acre\u00fana &#8211; GO, ficando <em>ad cautelum<\/em> cancelada a sua validade;<\/p>\n<p style=\"text-align: justify;\"><strong>RECOMENDO<\/strong> aos Ju\u00edzes de Direito Diretores dos F\u00f3runs, Membros do Minist\u00e9rio P\u00fablico, Advogados, Not\u00e1rios e Registradores, Serventu\u00e1rios e a quem mais possa interessar, que observem o Comunicado supra citado, e adotem as provid\u00eancias que entenderem pertinentes.<\/p>\n<p style=\"text-align: justify;\"><strong>Publique-se.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Cumpra-se.<\/strong><\/p>\n<p style=\"text-align: justify;\">Vit\u00f3ria\/ES, 30 de Outubro de 2012.<\/p>\n<p style=\"text-align: center;\"><strong>DES. CARLOS HENRIQUE RIOS DO AMARAL<br \/>\nCorregedor-Geral da Justi\u00e7a<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ESTADO DO ESP\u00cdRITO SANTO PODER JUDICI\u00c1RIO CORREGEDORIA GERAL DA JUSTI\u00c7A OF\u00cdCIO-CIRCULAR N\u00ba. 77\/2012 Protocolo n\u00ba 201201381238 O Exmo. Sr. Desembargador Corregedor-Geral da Justi\u00e7a do Estado do Esp\u00edrito Santo, no uso de suas atribui\u00e7\u00f5es legais: CONSIDERANDO o recebimento do Of\u00edcio Circular n\u00ba 162\/2012 &#8211; SEC da lavra do Excelent\u00edssima Desembargadora Corregedora-geral da Justi\u00e7a do Estado de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/12959"}],"collection":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/comments?post=12959"}],"version-history":[{"count":1,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/12959\/revisions"}],"predecessor-version":[{"id":12960,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/12959\/revisions\/12960"}],"wp:attachment":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/media?parent=12959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/categories?post=12959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/tags?post=12959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}