{"id":13350,"date":"2017-03-31T13:14:10","date_gmt":"2017-03-31T16:14:10","guid":{"rendered":"https:\/\/www.tjes.jus.br\/corregedoria\/?p=13350"},"modified":"2017-03-31T13:14:10","modified_gmt":"2017-03-31T16:14:10","slug":"ato-normativo-no-0372005-publ-24082005","status":"publish","type":"post","link":"https:\/\/www.tjes.jus.br\/corregedoria\/2017\/03\/31\/ato-normativo-no-0372005-publ-24082005\/","title":{"rendered":"ATO NORMATIVO N\u00ba 037\/2005 &#8211; PUBL. 24\/08\/2005"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>PODER JUDICI\u00c1RIO DO ESTADO DO ESP\u00cdRITO SANTO<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>TRIBUNAL DE JUSTI\u00c7A<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>ATO NORMATIVO N\u00ba 37\/2005<\/strong><\/p>\n<p style=\"text-align: justify;\">O Exmo. Sr. Desembargador Adalto Dias Trist\u00e3o, Presidente do Egr\u00e9gio Tribunal de Justi\u00e7a do Estado do Esp\u00edrito Santo, no uso de suas atribui\u00e7\u00f5es legais e,<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong> a necessidade do cadastramento no sistema intranet deste Tribunal, dos processos em tramita\u00e7\u00e3o na Comarca de Colatina, em atendimento a determina\u00e7\u00e3o contida no <a href=\"https:\/\/www.tjes.jus.br\/corregedoria\/index.php\/2017\/03\/31\/ato-normativo-no-0232005-publ-16062005\/\" target=\"_blank\">Ato Normativo n\u00ba 23\/2005<\/a>, publicado no Di\u00e1rio da Justi\u00e7a de 16 de junho de 2005;<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong> o disposto no art. 58 da Resolu\u00e7\u00e3o n\u00ba 15\/95 &#8211; Regimento Interno do Tribunal de Justi\u00e7a do Estado do Esp\u00edrito Santo, que atribui ao Presidente do Tribunal de Justi\u00e7a a compet\u00eancia geral para exercer a superintend\u00eancia de todo o servi\u00e7o judici\u00e1rio, na qualidade de Chefe da Magistratura do Estado,<\/p>\n<p style=\"text-align: justify;\"><strong>RESOLVE<\/strong>:<\/p>\n<p style=\"text-align: justify;\"><strong>SUSPENDER<\/strong> os prazos processuais pelo prazo de 30 (trinta) dias na Comarca de Colatina.<\/p>\n<p style=\"text-align: justify;\">Vit\u00f3ria, 22 de agosto de 2005.<\/p>\n<p style=\"text-align: center;\"><strong>Desembargador ADALTO DIAS TRIST\u00c3O<br \/>\nPresidente<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PODER JUDICI\u00c1RIO DO ESTADO DO ESP\u00cdRITO SANTO TRIBUNAL DE JUSTI\u00c7A ATO NORMATIVO N\u00ba 37\/2005 O Exmo. Sr. Desembargador Adalto Dias Trist\u00e3o, Presidente do Egr\u00e9gio Tribunal de Justi\u00e7a do Estado do Esp\u00edrito Santo, no uso de suas atribui\u00e7\u00f5es legais e, CONSIDERANDO a necessidade do cadastramento no sistema intranet deste Tribunal, dos processos em tramita\u00e7\u00e3o na Comarca [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,14],"tags":[],"_links":{"self":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/13350"}],"collection":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/comments?post=13350"}],"version-history":[{"count":1,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/13350\/revisions"}],"predecessor-version":[{"id":13351,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/13350\/revisions\/13351"}],"wp:attachment":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/media?parent=13350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/categories?post=13350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/tags?post=13350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}