{"id":19551,"date":"2017-10-02T13:45:59","date_gmt":"2017-10-02T16:45:59","guid":{"rendered":"https:\/\/www.tjes.jus.br\/corregedoria\/?p=19551"},"modified":"2017-10-02T13:45:59","modified_gmt":"2017-10-02T16:45:59","slug":"oficio-circular-no-0832010-publ-14102010","status":"publish","type":"post","link":"https:\/\/www.tjes.jus.br\/corregedoria\/2017\/10\/02\/oficio-circular-no-0832010-publ-14102010\/","title":{"rendered":"OF\u00cdCIO-CIRCULAR N\u00ba 083\/2010 &#8211; PUBL. 14\/10\/2010"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>ESTADO DO ESP\u00cdRITO SANTO<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>PODER JUDICI\u00c1RIO<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>CORREGEDORIA GERAL DA JUSTI\u00c7A<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>OF\u00cdCIO-CIRCULAR N\u00ba. 083\/2010<\/strong><\/p>\n<p style=\"text-align: justify;\">(Favor mencionar essa refer\u00eancia)<\/p>\n<p style=\"text-align: justify;\">O Exmo. Sr. Desembargador Corregedor-Geral da Justi\u00e7a do Estado do Esp\u00edrito Santo, Desembargador S\u00e9rgio Luiz Teixeira Gama, no uso de suas atribui\u00e7\u00f5es legais:<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong> que a Corregedoria Geral da Justi\u00e7a do Estado do Esp\u00edrito Santo \u00e9 \u00f3rg\u00e3o de fiscaliza\u00e7\u00e3o, disciplina e orienta\u00e7\u00e3o administrativa, com jurisdi\u00e7\u00e3o em todo Estado, conforme art. 2\u00ba da Lei complementar Estadual N\u00ba 83\/96.<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong> o movimento grevista no Banco do Estado do Esp\u00edrito Santo S\/A, culminando com a suspens\u00e3o do atendimento \u00e0 popula\u00e7\u00e3o, e que n\u00e3o h\u00e1 previs\u00e3o para seu fim;<\/p>\n<p style=\"text-align: justify;\"><strong>RESOLVE<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Art. 1\u00ba <\/strong>\u2013 Os valores relativos \u00e0s custas processuais e \u00e0 taxa judici\u00e1ria, em se tratando de medida urgente, enquanto n\u00e3o findar o movimento grevista no Banco do Estado do Esp\u00edrito Santo, dever\u00e3o ser recolhidas nas Contadorias Judiciais das respectivas Comarcas, em rela\u00e7\u00e3o aos feitos ali em andamento, nos termos do Art. 22 \u00a7 1\u00ba. da Lei Estadual 4.847\/93 \u2013 Regimento de Custas<\/p>\n<p style=\"text-align: justify;\"><strong>Art. 2\u00ba <\/strong>\u2013 Fica autorizada a posterga\u00e7\u00e3o dos recolhimentos dos valores relativos ao Fundo de Apoio ao Registro Civil das Pessoas Naturais do Estado do Esp\u00edrito Santo \u2013 FARPEN e os valores relativos a um d\u00e9cimo (1\/10) dos emolumentos incidentes sobre todos os atos realizados pelas serventias n\u00e3o oficializadas \u2013 C\u00f3digo 183 do FUNEPJ.<\/p>\n<p style=\"text-align: justify;\"><strong>Art. 3\u00ba <\/strong>\u2013 Os pedidos relativos aos Selos de Fiscaliza\u00e7\u00e3o ser\u00e3o liberados sem o pagamento pr\u00e9vio, enquanto n\u00e3o findar o movimento grevista no Banco do Estado do Esp\u00edrito Santo, sendo necess\u00e1ria a gera\u00e7\u00e3o imediata da guia de recolhimento \u2013 c\u00f3digo da receita 205 \u2013 e o encaminhamento da c\u00f3pia, por fax (27) 3324-8955, \u00e0 Auditoria Interna da Corregedoria Geral da Justi\u00e7a.<\/p>\n<p style=\"text-align: justify;\"><strong>Art. 4\u00ba <\/strong>\u2013 Os recolhimentos na forma dos artigos anteriores dever\u00e3o ser regularizados, junto ao BANESTES, no primeiro dia \u00fatil ap\u00f3s o encerramento do movimento grevista.<\/p>\n<p style=\"text-align: center;\"><strong>Des. S\u00c9RGIO LUIZ TEIXEIRA GAMA<br \/>\nCorregedor-Geral da Justi\u00e7a<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ESTADO DO ESP\u00cdRITO SANTO PODER JUDICI\u00c1RIO CORREGEDORIA GERAL DA JUSTI\u00c7A OF\u00cdCIO-CIRCULAR N\u00ba. 083\/2010 (Favor mencionar essa refer\u00eancia) O Exmo. Sr. Desembargador Corregedor-Geral da Justi\u00e7a do Estado do Esp\u00edrito Santo, Desembargador S\u00e9rgio Luiz Teixeira Gama, no uso de suas atribui\u00e7\u00f5es legais: CONSIDERANDO que a Corregedoria Geral da Justi\u00e7a do Estado do Esp\u00edrito Santo \u00e9 \u00f3rg\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/19551"}],"collection":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/comments?post=19551"}],"version-history":[{"count":1,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/19551\/revisions"}],"predecessor-version":[{"id":19552,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/19551\/revisions\/19552"}],"wp:attachment":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/media?parent=19551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/categories?post=19551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/tags?post=19551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}