{"id":19588,"date":"2017-10-02T14:47:36","date_gmt":"2017-10-02T17:47:36","guid":{"rendered":"https:\/\/www.tjes.jus.br\/corregedoria\/?p=19588"},"modified":"2017-10-02T14:47:36","modified_gmt":"2017-10-02T17:47:36","slug":"oficio-circular-no-0982010-publ-22112010","status":"publish","type":"post","link":"https:\/\/www.tjes.jus.br\/corregedoria\/2017\/10\/02\/oficio-circular-no-0982010-publ-22112010\/","title":{"rendered":"OF\u00cdCIO-CIRCULAR N\u00ba 098\/2010 &#8211; PUBL. 22\/11\/2010"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>ESTADO DO ESP\u00cdRITO SANTO<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>PODER JUDICI\u00c1RIO<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>CORREGEDORIA GERAL DA JUSTI\u00c7A<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>OF\u00cdCIO-CIRCULAR N\u00ba 098\/2010<\/strong><\/p>\n<p style=\"text-align: justify;\">Vit\u00f3ria\/ES, 16 de novembro de 2010.<\/p>\n<p style=\"text-align: justify;\">Aos Senhores Oficiais de Cart\u00f3rio de Registro Civil de Pessoas Jur\u00eddicas e Senhores Ju\u00edzes de Direito com compet\u00eancia em mat\u00e9ria de Registros P\u00fablicos:<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong> ser a Corregedoria Geral da Justi\u00e7a \u00f3rg\u00e3o de fiscaliza\u00e7\u00e3o, que disciplina a orienta\u00e7\u00e3o administrativa dos Juizados de Direito e das serventias do foro extrajudicial, com jurisdi\u00e7\u00e3o em todo o Estado, conforme art. 35 da Lei Complementar Estadual n\u00ba 234\/02 e art. 37 da Lei Federal n.\u00ba 8.935\/94;<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong> recente decis\u00e3o administrativa proferida no bojo do processo CGJES n.\u00ba 1028136 que acolheu o pleito formulado pela CRUZ VERMELHA DO BRASIL no sentido de determinar aos Cart\u00f3rios de Registro Civil de Pessoas Jur\u00eddicas e\/ou de T\u00edtulos e Documentos deste Estado que se abstenham de registrar estatutos de cria\u00e7\u00e3o de filiais sem a devida e expressa autoriza\u00e7\u00e3o daquele \u00f3rg\u00e3o central.<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong> que a legisla\u00e7\u00e3o atinente \u00e0 mat\u00e9ria &#8211; Decreto Federal n.\u00ba 23.482, de 21 de novembro de 1933 &#8211; contempla expressamente a exig\u00eancia de pr\u00e9via autoriza\u00e7\u00e3o por parte da Sociedade Cruz Vermelha Brasileira para cria\u00e7\u00e3o de filiais por iniciativa particular no territ\u00f3rio nacional.<\/p>\n<p style=\"text-align: justify;\"><strong>RESOLVE<\/strong>:<\/p>\n<p style=\"text-align: justify;\"><strong>Art. 1\u00ba <\/strong>&#8211; <strong>ORIENTAR<\/strong> os Senhores Oficiais dos Cart\u00f3rios de Registro Civil de Pessoas Jur\u00eddicas a observarem fielmente os termos do art. 911, \u00a72\u00ba, do CNCGJES na hip\u00f3tese de pedido de registro\/reconhecimento de filial da Sociedade Cruz Vermelha Brasileira no territ\u00f3rio do Estado do Esp\u00edrito Santo, devendo providenciar as averba\u00e7\u00f5es necess\u00e1rias junto ao servi\u00e7o registral de id\u00eantica natureza situado na Sede do Munic\u00edpio do Rio de Janeiro\/RJ (Decreto Federal n.\u00ba 23.482, de 21 de novembro de 1933).<\/p>\n<p style=\"text-align: justify;\"><strong>Art. 2\u00ba <\/strong>&#8211; <strong>ORIENTAR<\/strong> os MM. Ju\u00edzes de Direito com compet\u00eancia em mat\u00e9ria de Registros P\u00fablicos a realizarem a fiscaliza\u00e7\u00e3o acerca do cumprimento do art. 911, \u00a72\u00ba do CNCGJES por ocasi\u00e3o das inspe\u00e7\u00f5es dos Servi\u00e7os Notariais e de Registro previstas no \u00a76\u00ba do art. 11 do C\u00f3digo de Normas.<\/p>\n<p style=\"text-align: justify;\"><strong>Publique-se. Registre-se. Cumpra-se.<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>DES. S\u00c9RGIO LUIZ TEIXEIRA GAMA<br \/>\nCorregedor-Geral da Justi\u00e7a<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ESTADO DO ESP\u00cdRITO SANTO PODER JUDICI\u00c1RIO CORREGEDORIA GERAL DA JUSTI\u00c7A OF\u00cdCIO-CIRCULAR N\u00ba 098\/2010 Vit\u00f3ria\/ES, 16 de novembro de 2010. Aos Senhores Oficiais de Cart\u00f3rio de Registro Civil de Pessoas Jur\u00eddicas e Senhores Ju\u00edzes de Direito com compet\u00eancia em mat\u00e9ria de Registros P\u00fablicos: CONSIDERANDO ser a Corregedoria Geral da Justi\u00e7a \u00f3rg\u00e3o de fiscaliza\u00e7\u00e3o, que disciplina a [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/19588"}],"collection":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/comments?post=19588"}],"version-history":[{"count":1,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/19588\/revisions"}],"predecessor-version":[{"id":19589,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/19588\/revisions\/19589"}],"wp:attachment":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/media?parent=19588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/categories?post=19588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/tags?post=19588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}