{"id":20169,"date":"2017-10-17T13:27:47","date_gmt":"2017-10-17T15:27:47","guid":{"rendered":"https:\/\/www.tjes.jus.br\/corregedoria\/?p=20169"},"modified":"2017-10-17T13:27:47","modified_gmt":"2017-10-17T15:27:47","slug":"oficio-circular-no-1852011-publ-25072011","status":"publish","type":"post","link":"https:\/\/www.tjes.jus.br\/corregedoria\/2017\/10\/17\/oficio-circular-no-1852011-publ-25072011\/","title":{"rendered":"OF\u00cdCIO-CIRCULAR N\u00ba 185\/2011 &#8211; PUBL. 25\/07\/2011"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>ESTADO DO ESP\u00cdRITO SANTO<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>PODER JUDICI\u00c1RIO<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>TRIBUNAL DE JUSTI\u00c7A<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Corregedoria Geral de Justi\u00e7a<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>OF\u00cdCIO-CIRCULAR N\u00ba 185\/2011.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Vit\u00f3ria\/ES, 25 de julho de 2011.<\/strong><\/p>\n<p style=\"text-align: justify;\">Senhores Ju\u00edzes de Direito atuantes na \u00e1rea de Registros P\u00fablicos:<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong> que a Corregedoria Geral da Justi\u00e7a \u00e9 \u00f3rg\u00e3o de fiscaliza\u00e7\u00e3o, disciplina e orienta\u00e7\u00e3o administrativa, com jurisdi\u00e7\u00e3o em todo o Estado, conforme art. 2\u00ba da Lei Complementar Estadual n\u00ba 83\/96 e art. 35 da Lei Complementar Estadual n\u00ba 234\/02;<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong> o teor do Provimento n\u00ba 12, de 06 de agosto de 2010, do Conselho Nacional de Justi\u00e7a, que disp\u00f5e acerca da ado\u00e7\u00e3o de medidas visando \u00e0 averigua\u00e7\u00e3o e ao reconhecimento de paternidade de alunos para os quais n\u00e3o existe informa\u00e7\u00e3o sobre o nome do pai.<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong>, finalmente, a constata\u00e7\u00e3o das dificuldades encontradas na implementa\u00e7\u00e3o das a\u00e7\u00f5es necess\u00e1rias e cab\u00edveis para dar efetividade \u00e0s prescri\u00e7\u00f5es constantes no Provimento n\u00ba 12 CNJ, sentidas n\u00e3o s\u00f3 pelo Estado do Esp\u00edrito Santo, mas por v\u00e1rios outros Estados da Federa\u00e7\u00e3o, compartilhada, inclusive, pela AMB, fato que levou, inclusive, \u00e0 publica\u00e7\u00e3o do Of\u00edcio n\u00ba 1.024\/2010 desta Corregedoria;<\/p>\n<p style=\"text-align: justify;\"><strong>RESOLVE<\/strong>:<\/p>\n<p style=\"text-align: justify;\"><strong>Art. 1\u00ba <\/strong>&#8211; <strong>DETERMINAR<\/strong> aos MM. Ju\u00edzes de Direito do Poder Judici\u00e1rio do Estado do Esp\u00edrito Santo, com compet\u00eancia em mat\u00e9ria de Registros P\u00fablicos, que cumpram o referido Provimento n\u00ba 12, de acordo com as possibilidades f\u00e1ticas e operacionais de cada Vara\/Comarca, com a implementa\u00e7\u00e3o das medidas necess\u00e1rias para a satisfat\u00f3ria execu\u00e7\u00e3o do Provimento.<\/p>\n<p style=\"text-align: justify;\"><strong>Publique-se. Registre-se. Cumpra-se.<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>DES. S\u00c9RGIO LUIZ TEIXEIRA GAMA<br \/>\nCorregedor-Geral da Justi\u00e7a<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ESTADO DO ESP\u00cdRITO SANTO PODER JUDICI\u00c1RIO TRIBUNAL DE JUSTI\u00c7A Corregedoria Geral de Justi\u00e7a OF\u00cdCIO-CIRCULAR N\u00ba 185\/2011. Vit\u00f3ria\/ES, 25 de julho de 2011. Senhores Ju\u00edzes de Direito atuantes na \u00e1rea de Registros P\u00fablicos: CONSIDERANDO que a Corregedoria Geral da Justi\u00e7a \u00e9 \u00f3rg\u00e3o de fiscaliza\u00e7\u00e3o, disciplina e orienta\u00e7\u00e3o administrativa, com jurisdi\u00e7\u00e3o em todo o Estado, conforme art. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/20169"}],"collection":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/comments?post=20169"}],"version-history":[{"count":1,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/20169\/revisions"}],"predecessor-version":[{"id":20170,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/20169\/revisions\/20170"}],"wp:attachment":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/media?parent=20169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/categories?post=20169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/tags?post=20169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}