{"id":20242,"date":"2017-10-17T17:26:39","date_gmt":"2017-10-17T19:26:39","guid":{"rendered":"https:\/\/www.tjes.jus.br\/corregedoria\/?p=20242"},"modified":"2017-10-17T17:26:39","modified_gmt":"2017-10-17T19:26:39","slug":"oficio-circular-no-2262011-publ-23112011","status":"publish","type":"post","link":"https:\/\/www.tjes.jus.br\/corregedoria\/2017\/10\/17\/oficio-circular-no-2262011-publ-23112011\/","title":{"rendered":"OF\u00cdCIO-CIRCULAR N\u00ba 226\/2011 &#8211; PUBL. 23\/11\/2011"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>ESTADO DO ESP\u00cdRITO SANTO<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>PODER JUDICI\u00c1RIO<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>CORREGEDORIA GERAL DA JUSTI\u00c7A<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>OF\u00cdCIO-CIRCULAR N\u00ba 226\/2011<\/strong><\/p>\n<p style=\"text-align: justify;\">Vit\u00f3ria\/ES, 21 de novembro de 2011.<\/p>\n<p style=\"text-align: justify;\">Aos Ju\u00edzes de Direito e \u00e0s Serventias do Estado do Esp\u00edrito Santo:<\/p>\n<p style=\"text-align: justify;\">O Exmo. Corregedor Geral da Justi\u00e7a, Desembargador S\u00e9rgio Luiz Teixeira Gama, no exerc\u00edcio de suas atribui\u00e7\u00f5es legais e regimentais, e<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong> que a Corregedoria Geral da Justi\u00e7a \u00e9 \u00f3rg\u00e3o de fiscaliza\u00e7\u00e3o, disciplina e orienta\u00e7\u00e3o administrativa, com jurisdi\u00e7\u00e3o em todo o Estado, conforme o art. 2\u00ba da Lei Complementar Estadual n\u00ba 83\/96 e o art. 35 da Lei Complementar Estadual n\u00ba 234\/02;<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong> a solicita\u00e7\u00e3o da Ordem dos Advogados do Brasil &#8211; Seccional de Vila Velha no \u00e2mbito do processo administrativo CGJES n\u00ba 1102750, por meio de que solicitou, atrav\u00e9s do Of\u00edcio n\u00ba 058\/2010, as provid\u00eancias necess\u00e1rias para <strong>determinar<\/strong> que as serventias, independentemente de apresenta\u00e7\u00e3o de andamento processual, procedessem a busca dos autos solicitados no balc\u00e3o pelos advogados, desde que apresentados corretamente o n\u00famero e\/ou nome das partes.<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong> o teor da decis\u00e3o de reconsidera\u00e7\u00e3o por mim exarada nos autos do processo CGJES n\u00ba 1102750, \u00e0s fls. 18\/20;<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong>, por fim, a necessidade de se regulamentar a mat\u00e9ria, evitando diverg\u00eancias de entendimento entre as diversas serventias existentes em nosso Estado.<\/p>\n<p style=\"text-align: justify;\"><strong>RESOLVE<\/strong>:<\/p>\n<p style=\"text-align: justify;\"><strong>Art. 1\u00ba <\/strong>&#8211; <strong>ORIENTAR<\/strong> aos magistrados e serventu\u00e1rios que procedam a busca dos autos solicitados no balc\u00e3o pelos advogados independentemente de apresenta\u00e7\u00e3o do respectivo andamento processual, desde que lhes sejam apresentadas as corretas e exatas informa\u00e7\u00f5es quanto ao n\u00famero e\/ou nome das partes litigantes.<\/p>\n<p style=\"text-align: justify;\"><strong>Publique-se. Registre-se. Cumpra-se.<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>DES. S\u00c9RGIO LUIZ TEIXEIRA GAMA<br \/>\nCorregedor-Geral da Justi\u00e7a<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ESTADO DO ESP\u00cdRITO SANTO PODER JUDICI\u00c1RIO CORREGEDORIA GERAL DA JUSTI\u00c7A OF\u00cdCIO-CIRCULAR N\u00ba 226\/2011 Vit\u00f3ria\/ES, 21 de novembro de 2011. Aos Ju\u00edzes de Direito e \u00e0s Serventias do Estado do Esp\u00edrito Santo: O Exmo. Corregedor Geral da Justi\u00e7a, Desembargador S\u00e9rgio Luiz Teixeira Gama, no exerc\u00edcio de suas atribui\u00e7\u00f5es legais e regimentais, e CONSIDERANDO que a Corregedoria [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/20242"}],"collection":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/comments?post=20242"}],"version-history":[{"count":1,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/20242\/revisions"}],"predecessor-version":[{"id":20243,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/20242\/revisions\/20243"}],"wp:attachment":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/media?parent=20242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/categories?post=20242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/tags?post=20242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}