{"id":20297,"date":"2017-10-18T14:03:54","date_gmt":"2017-10-18T16:03:54","guid":{"rendered":"https:\/\/www.tjes.jus.br\/corregedoria\/?p=20297"},"modified":"2017-10-18T14:21:41","modified_gmt":"2017-10-18T16:21:41","slug":"oficio-circular-no-252012-publ-20032012","status":"publish","type":"post","link":"https:\/\/www.tjes.jus.br\/corregedoria\/2017\/10\/18\/oficio-circular-no-252012-publ-20032012\/","title":{"rendered":"OF\u00cdCIO-CIRCULAR N\u00ba 25\/2012 &#8211; PUBL. 20\/03\/2012"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>ESTADO DO ESP\u00cdRITO SANTO<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>PODER JUDICI\u00c1RIO<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>CORREGEDORIA GERAL DA JUSTI\u00c7A<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>OF\u00cdCIO-CIRCULAR N.\u00ba 25\/2012<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Vit\u00f3ria(ES), 16 de mar\u00e7o de 2012<\/strong><\/p>\n<p style=\"text-align: justify;\">Senhores(as) Ju\u00edzes(as) de Direito,<\/p>\n<p style=\"text-align: justify;\">Por meio do <a href=\"https:\/\/www.tjes.jus.br\/corregedoria\/wp-content\/uploads\/2016\/06\/Provimento_09-2012.pdf\" target=\"_blank\" rel=\"noopener\">Provimento n.\u00ba 09\/2012<\/a>, datado desta data, constitu\u00ed Comiss\u00e3o integrada por 04 (quatro) magistrados e 05 (cinco) servidores para analisar a necessidade\/utilidade dos in\u00fameros livros obrigat\u00f3rios que o C\u00f3digo de Normas imp\u00f5e que existam nas serventias judiciais.<\/p>\n<p style=\"text-align: justify;\">Em um exame superficial, constata-se serem aproximadamente 40 (quarenta) os livros exigidos nos arts. 303 a 310 do C\u00f3digo de Normas.<\/p>\n<p style=\"text-align: justify;\">Considero indispens\u00e1vel repensar se todos esses livros ainda se fazem necess\u00e1rios diante da moderniza\u00e7\u00e3o ocorrida nas atividades das serventias, originadas, principalmente, da informatiza\u00e7\u00e3o dos sistemas de gerenciamento dos processos.<\/p>\n<p style=\"text-align: justify;\">Ademais, os servidores est\u00e3o com um volume de atividades imenso, impondo que toda e qualquer medida administrativa que possa evitar retrabalho e aumentar a efici\u00eancia operacional das serventias deve ser buscada e, principalmente, implementada, com absoluta prioridade.<\/p>\n<p style=\"text-align: justify;\">Portanto, solicito a todos os colegas magistrados que contribuam com os trabalhos da Comiss\u00e3o e incentivem os servidores da unidade jurisdicional na qual atuam a tamb\u00e9m o fazerem.<\/p>\n<p style=\"text-align: justify;\">As sugest\u00f5es devem ser encaminhadas, no prazo de 05 (cinco) dias, para o endere\u00e7o eletr\u00f4nico <a href=\"mailto:secretariacgj@tjes.jus.br\">secretariacgj@tjes.jus.br<\/a>, com a indica\u00e7\u00e3o do assunto \u2018LIVROS OBRIGAT\u00d3RIOS\u2019. <strong>(Errata publicada em 22\/03\/2012)<\/strong><\/p>\n<p style=\"text-align: justify;\">No aguardo das sugest\u00f5es ora solicitadas, reafirmo meu apre\u00e7o pessoal.<\/p>\n<p style=\"text-align: justify;\">Atenciosamente,<\/p>\n<p style=\"text-align: center;\"><strong>Des. CARLOS HENRIQUE RIOS DO AMARAL<br \/>\nCorregedor-Geral da Justi\u00e7a<\/strong><\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #ff0000;\">ERRATA PUBLICADA EM 22\/03\/2012 (<a href=\"https:\/\/www.tjes.jus.br\/corregedoria\/2017\/10\/18\/errata-publicada-em-22032012-nos-oficios-circulares-252012-e-262012\/\" target=\"_blank\" rel=\"noopener\">CLIQUE AQUI<\/a>)<\/span><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>ESTADO DO ESP\u00cdRITO SANTO PODER JUDICI\u00c1RIO CORREGEDORIA GERAL DA JUSTI\u00c7A OF\u00cdCIO-CIRCULAR N.\u00ba 25\/2012 Vit\u00f3ria(ES), 16 de mar\u00e7o de 2012 Senhores(as) Ju\u00edzes(as) de Direito, Por meio do Provimento n.\u00ba 09\/2012, datado desta data, constitu\u00ed Comiss\u00e3o integrada por 04 (quatro) magistrados e 05 (cinco) servidores para analisar a necessidade\/utilidade dos in\u00fameros livros obrigat\u00f3rios que o C\u00f3digo de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/20297"}],"collection":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/comments?post=20297"}],"version-history":[{"count":3,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/20297\/revisions"}],"predecessor-version":[{"id":20307,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/20297\/revisions\/20307"}],"wp:attachment":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/media?parent=20297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/categories?post=20297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/tags?post=20297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}