{"id":22911,"date":"2018-02-23T17:53:45","date_gmt":"2018-02-23T20:53:45","guid":{"rendered":"https:\/\/www.tjes.jus.br\/corregedoria\/?p=22911"},"modified":"2018-02-23T17:53:45","modified_gmt":"2018-02-23T20:53:45","slug":"oficio-circular-no-141-2015-disp-16-09-2015","status":"publish","type":"post","link":"https:\/\/www.tjes.jus.br\/corregedoria\/2018\/02\/23\/oficio-circular-no-141-2015-disp-16-09-2015\/","title":{"rendered":"OF\u00cdCIO-CIRCULAR N\u00ba 141\/2015 &#8211; DISP. 16\/09\/2015"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>ESTADO DO ESP\u00cdRITO SANTO<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>PODER JUDICI\u00c1RIO<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>CORREGEDORIA GERAL DA JUSTI\u00c7A<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>OF\u00cdCIO-CIRCULAR N\u00ba 141\/2015<\/strong><\/p>\n<p style=\"text-align: justify;\">Vit\u00f3ria\/ES, 31 de julho de 2015.<\/p>\n<p style=\"text-align: justify;\">O Desembargador <strong>RONALDO GON\u00c7ALVES DE SOUSA, <\/strong>Corregedor-Geral da Justi\u00e7a, no uso de suas atribui\u00e7\u00f5es, e<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong> o disposto no <a href=\"http:\/\/www.cnj.jus.br\/busca-atos-adm?documento=2438\" target=\"_blank\" rel=\"noopener\">Provimento n.\u00ba 16\/2012, da Corregedoria Nacional de Justi\u00e7a<\/a>, que disp\u00f5e sobre a recep\u00e7\u00e3o pelos Oficiais de Registro Civil das Pessoas Naturais, de indica\u00e7\u00f5es de supostos pais de pessoas que j\u00e1 se acharem registradas sem paternidade estabelecida, bem como sobre o reconhecimento espont\u00e2neo de filhos perante os referidos registradores;<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong> o teor da Lei n\u00ba 8.560\/1992, que regula a investiga\u00e7\u00e3o de paternidade dos filhos havidos fora do casamento e d\u00e1 outras provid\u00eancias;<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong>, que a al\u00ednea <em>\u201ce\u201d,<\/em> inciso I, do artigo 61, da Lei Complementar n\u00ba 234\/02, prev\u00ea que<em> \u201ccompete aos ju\u00edzes de direito, especialmente em mat\u00e9ria de fam\u00edlia, processar e julgar as a\u00e7\u00f5es de investiga\u00e7\u00e3o de paternidade cumuladas ou n\u00e3o com as de peti\u00e7\u00e3o de heran\u00e7a e as averigua\u00e7\u00f5es oficiosas de paternidade\u201d;<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong>, por fim, que a Corregedoria Geral da Justi\u00e7a \u00e9 \u00f3rg\u00e3o de fiscaliza\u00e7\u00e3o, disciplina e orienta\u00e7\u00e3o administrativa, com jurisdi\u00e7\u00e3o em todo o Estado, conforme artigo 35, da Lei Complementar Estadual n\u00ba 234\/02.<\/p>\n<p style=\"text-align: justify;\"><strong>RESOLVE:<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Art. 1\u00ba \u2013 Determinar<\/strong> aos MM Ju\u00edzes de Direito com compet\u00eancia em mat\u00e9ria de Fam\u00edlia que observem, com rela\u00e7\u00e3o ao procedimento de averigua\u00e7\u00e3o oficiosa de paternidade, o estabelecido na Lei n\u00ba 8.560\/1992 c\/c o <a href=\"http:\/\/www.cnj.jus.br\/busca-atos-adm?documento=2438\" target=\"_blank\" rel=\"noopener\">Provimento n\u00ba 16\/2012, da Corregedoria Nacional de Justi\u00e7a<\/a>, bem como para que efetuem o cadastro do procedimento em comento de acordo com as Classes das Tabelas Processuais Unificadas do Conselho Nacional de Justi\u00e7a.<\/p>\n<p style=\"text-align: justify;\"><strong>Publique-se. Registre-se. Cumpra-se.<\/strong><\/p>\n<p style=\"text-align: justify;\">Vit\u00f3ria\/ES, 31 de julho de 2015.<\/p>\n<p style=\"text-align: center;\"><strong>Desembargador RONALDO GON\u00c7ALVES DE SOUSA<br \/>\nCorregedor-Geral da Justi\u00e7a<\/strong><\/p>\n<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.tjes.jus.br\/corregedoria\/wp-content\/uploads\/2018\/02\/Oficio_Circular_141-2015_Anexo_Provimento_CNJ_16-2012.pdf\" target=\"_blank\" rel=\"noopener\">Provimento n\u00ba 16 &#8211; Conselho Nacional de Justi\u00e7a<\/a><\/strong><\/p>\n<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.tjes.jus.br\/corregedoria\/wp-content\/uploads\/2018\/02\/Oficio_Circular_141-2015_Anexo_Tabela_CNJ.pdf\" target=\"_blank\" rel=\"noopener\">ANEXO I<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ESTADO DO ESP\u00cdRITO SANTO PODER JUDICI\u00c1RIO CORREGEDORIA GERAL DA JUSTI\u00c7A OF\u00cdCIO-CIRCULAR N\u00ba 141\/2015 Vit\u00f3ria\/ES, 31 de julho de 2015. O Desembargador RONALDO GON\u00c7ALVES DE SOUSA, Corregedor-Geral da Justi\u00e7a, no uso de suas atribui\u00e7\u00f5es, e CONSIDERANDO o disposto no Provimento n.\u00ba 16\/2012, da Corregedoria Nacional de Justi\u00e7a, que disp\u00f5e sobre a recep\u00e7\u00e3o pelos Oficiais de Registro [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/22911"}],"collection":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/comments?post=22911"}],"version-history":[{"count":1,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/22911\/revisions"}],"predecessor-version":[{"id":22914,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/22911\/revisions\/22914"}],"wp:attachment":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/media?parent=22911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/categories?post=22911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/tags?post=22911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}