{"id":26384,"date":"2019-02-26T13:12:31","date_gmt":"2019-02-26T16:12:31","guid":{"rendered":"https:\/\/www.tjes.jus.br\/corregedoria\/?p=26384"},"modified":"2019-02-28T12:50:10","modified_gmt":"2019-02-28T15:50:10","slug":"ato-normativo-no-022-2019-disp-26-02-2019","status":"publish","type":"post","link":"https:\/\/www.tjes.jus.br\/corregedoria\/2019\/02\/26\/ato-normativo-no-022-2019-disp-26-02-2019\/","title":{"rendered":"ATO NORMATIVO N\u00ba 022 \/2019 &#8211; DISP. 26\/02\/2019"},"content":{"rendered":"<p align=\"center\">ESTADO DO ESP\u00cdRITO SANTO<\/p>\n<p align=\"center\">PODER JUDICI\u00c1RIO<\/p>\n<p align=\"center\">TRIBUNAL DE JUSTI\u00c7A<\/p>\n<p align=\"center\"><i>GABINETE DA PRESID\u00caNCIA<\/i><\/p>\n<p align=\"center\"><strong>ATO NORMATIVO n\u00ba 022 \/2019<\/strong><\/p>\n<p align=\"justify\">O Excelent\u00edssimo Senhor Desembargador S\u00e9rgio Luiz Teixeira Gama, Presidente do Egr\u00e9gio Tribunal de Justi\u00e7a do Estado do Esp\u00edrito Santo, no uso de suas atribui\u00e7\u00f5es legais,<\/p>\n<p align=\"justify\">CONSIDERANDO o teor do expediente protocolado neste Egr\u00e9gio Tribunal de Justi\u00e7a sob o n\u00famero 2019.00.252.760, encaminhado pelo Exmo. Sr. Dr. Carlos Madeira Abad, por meio do qual requer a prorroga\u00e7\u00e3o da suspens\u00e3o dos prazos na <del>Vara da Inf\u00e2ncia e Juventude da Comarca de Linhares<\/del>\u00a02\u00aa Vara da Inf\u00e2ncia e Juventude da Comarca de Linhares <strong><span style=\"color: #ff0000;\">(Alterado pela <a href=\"https:\/\/www.tjes.jus.br\/corregedoria\/2019\/02\/28\/errata-do-ato-normativo-n-22-2019-disp-28-02-2019\/\" target=\"_blank\" rel=\"noopener\">errata to ato normativo n\u00b0 22\/2019<\/a>)<\/span><\/strong> at\u00e9 o dia 25\/02\/2019, ap\u00f3s a publica\u00e7\u00e3o do <a href=\"https:\/\/www.tjes.jus.br\/corregedoria\/2019\/02\/20\/ato-normativo-no-016-2019-disp-20-02-2019\/\" target=\"_blank\" rel=\"noopener\">Ato Normativo n\u00ba 016\/2019<\/a>;<\/p>\n<p align=\"justify\">CONSIDERANDO que o Magistrado informa a realiza\u00e7\u00e3o de pintura do cart\u00f3rio daquela unidade e a necessidade de reorganiza\u00e7\u00e3o dos processos e dos equipamentos, o que inviabilizar\u00e1 o regular desempenho das atividades forenses;<\/p>\n<p align=\"justify\">RESOLVE:<\/p>\n<p align=\"justify\">SUSPENDER os prazos na Vara da Inf\u00e2ncia e Juventude da Comarca de Linhares no dia 25\/02\/2019, sem preju\u00edzo da an\u00e1lise das medidas urgentes.<\/p>\n<p align=\"justify\"><span lang=\"pt-BR\">Publique-se.<\/span><\/p>\n<p align=\"center\"><span lang=\"pt-BR\">Vit\u00f3ria, 25 de Fevereiro de 2019.<\/span><\/p>\n<p align=\"center\"><span lang=\"pt-BR\">Desembargador S\u00c9RGIO LUIZ TEIXEIRA GAMA<\/span><\/p>\n<p align=\"center\"><span lang=\"pt-BR\">Presidente<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ESTADO DO ESP\u00cdRITO SANTO PODER JUDICI\u00c1RIO TRIBUNAL DE JUSTI\u00c7A GABINETE DA PRESID\u00caNCIA ATO NORMATIVO n\u00ba 022 \/2019 O Excelent\u00edssimo Senhor Desembargador S\u00e9rgio Luiz Teixeira Gama, Presidente do Egr\u00e9gio Tribunal de Justi\u00e7a do Estado do Esp\u00edrito Santo, no uso de suas atribui\u00e7\u00f5es legais, CONSIDERANDO o teor do expediente protocolado neste Egr\u00e9gio Tribunal de Justi\u00e7a sob o [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/26384"}],"collection":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/comments?post=26384"}],"version-history":[{"count":3,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/26384\/revisions"}],"predecessor-version":[{"id":26420,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/26384\/revisions\/26420"}],"wp:attachment":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/media?parent=26384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/categories?post=26384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/tags?post=26384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}