{"id":28110,"date":"2019-10-16T15:40:17","date_gmt":"2019-10-16T18:40:17","guid":{"rendered":"https:\/\/www.tjes.jus.br\/corregedoria\/?p=28110"},"modified":"2019-10-16T15:43:49","modified_gmt":"2019-10-16T18:43:49","slug":"ato-normativo-no-135-2019-disp-07-10-2019","status":"publish","type":"post","link":"https:\/\/www.tjes.jus.br\/corregedoria\/2019\/10\/16\/ato-normativo-no-135-2019-disp-07-10-2019\/","title":{"rendered":"ATO NORMATIVO N\u00ba 135\/2019 \u2013 DISP. 07\/10\/2019"},"content":{"rendered":"<p align=\"center\"><strong>ESTADO DO ESP\u00cdRITO SANTO \u2013 PODER JUDICI\u00c1RIO<\/strong><\/p>\n<p align=\"center\"><strong>TRIBUNAL DE JUSTI\u00c7A<\/strong><\/p>\n<p align=\"center\"><strong>PRESID\u00caNCIA<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><strong>Ato Normativo N\u00ba 135\/2019<\/strong><\/p>\n<p align=\"justify\">Altera parcialmente os Atos Normativos n\u00b0s <a href=\"https:\/\/www.tjes.jus.br\/corregedoria\/2019\/08\/28\/ato-normativo-no-118-2019-disp-28-08-2019\/\">118\/2019<\/a> e <a href=\"https:\/\/www.tjes.jus.br\/corregedoria\/2019\/10\/15\/ato-normativo-no-132-2019-disp-01-10-2019\/\">132\/2019<\/a>, que institu\u00edram e convocaram a equipe de trabalho que atuar\u00e1 na Pauta Concentrada de Media\u00e7\u00e3o em Cachoeiro de Itapemirim.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">O Excelent\u00edssimo Senhor Desembargador S\u00c9RGIO LUIZ TEIXEIRA GAMA, Presidente do Egr\u00e9gio Tribunal de Justi\u00e7a do Estado do Esp\u00edrito Santo, no uso de suas atribui\u00e7\u00f5es legais e,<\/p>\n<p style=\"text-align: justify;\" align=\"justify\"><span lang=\"pt-BR\">CONSIDERANDO os termos do<\/span><span lang=\"pt-BR\">s<\/span><span lang=\"pt-BR\">\u00a0Ato<\/span><span lang=\"pt-BR\">s<\/span><span lang=\"pt-BR\">\u00a0Normativo<\/span><span lang=\"pt-BR\">s<\/span><span lang=\"pt-BR\">\u00a0n\u00ba<\/span><span lang=\"pt-BR\">s\u00a0<\/span><a href=\"https:\/\/www.tjes.jus.br\/corregedoria\/2019\/08\/28\/ato-normativo-no-118-2019-disp-28-08-2019\/\"><span lang=\"pt-BR\">118<\/span><\/a><span lang=\"pt-BR\"><a href=\"https:\/\/www.tjes.jus.br\/corregedoria\/2019\/08\/28\/ato-normativo-no-118-2019-disp-28-08-2019\/\">\/2019<\/a>\u00a0<\/span><span lang=\"pt-BR\">e\u00a0<\/span><a href=\"https:\/\/www.tjes.jus.br\/corregedoria\/2019\/10\/15\/ato-normativo-no-132-2019-disp-01-10-2019\/\"><span lang=\"pt-BR\">132<\/span><span lang=\"pt-BR\">\/2019<\/span><\/a><span lang=\"pt-BR\">, publicado<\/span><span lang=\"pt-BR\">s<\/span><span lang=\"pt-BR\">\u00a0no Di\u00e1rio da Justi\u00e7a de 2<\/span><span lang=\"pt-BR\">8<\/span><span lang=\"pt-BR\">\/08\/2019\u00a0<\/span><span lang=\"pt-BR\">e\u00a0<\/span><span lang=\"pt-BR\">01\/10\/2019<\/span><span lang=\"pt-BR\">, respectivamente,\u00a0<\/span><span lang=\"pt-BR\">que\u00a0<\/span><span lang=\"pt-BR\">d<\/span><span lang=\"pt-BR\">esignou Magistrados e\u00a0<\/span><span lang=\"pt-BR\">S<\/span><span lang=\"pt-BR\">ervidores para a atua\u00e7\u00e3o\u00a0<\/span>no per\u00edodo de 07\/10\/19 a 09\/10\/19 e 21\/10\/2019 a 25\/10\/2019, no hor\u00e1rio das 8h00min \u00e0s 18h00min, nas depend\u00eancias da Faculdade de Direito de Cachoeiro de Itapemirim \u2013 FDCI, localizada na Rodovia Engenheiro Fabiano Vivacqua \u2013 BR 482, n\u00ba 1759 e 1877 \u2013 2\u00ba andar \u2013 Morro Grande, Cachoeiro de Itapemirim\/ES<\/p>\n<p align=\"left\">RESOLVE:<\/p>\n<p align=\"justify\">Art. 1\u00ba \u2013\u00a0Alterar a\u00a0composi\u00e7\u00e3o do artigo\u00a01\u00ba\u00a0do <a href=\"https:\/\/www.tjes.jus.br\/corregedoria\/2019\/10\/15\/ato-normativo-no-132-2019-disp-01-10-2019\/\">Ato Normativo n\u00ba\u00a0132\/2019<\/a>, publicado\u00a0no Di\u00e1rio da Justi\u00e7a em\u00a001de\u00a0outubro\u00a0do corrente\u00a0ano, para\u00a0incluir\u00a0as seguintes servidoras<strong>:<\/strong><\/p>\n<table cellspacing=\"0\" cellpadding=\"2\">\n<colgroup>\n<col width=\"353\" \/>\n<col width=\"279\" \/><\/colgroup>\n<tbody>\n<tr valign=\"top\">\n<td width=\"353\">\n<p align=\"justify\">Izabella Dalla Sily Casagrande<\/p>\n<\/td>\n<td width=\"279\">\n<p align=\"justify\">Mediadora Judicial<\/p>\n<\/td>\n<\/tr>\n<tr valign=\"top\">\n<td width=\"353\">\n<p align=\"justify\">Juliana da Silva Agostini<\/p>\n<\/td>\n<td width=\"279\">\n<p align=\"justify\">Mediadora Judicial<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p align=\"justify\">Art. 3\u00ba \u2013 Este Ato Normativo entra em vigor na data de sua publica\u00e7\u00e3o, revogando-se as disposi\u00e7\u00f5es em contr\u00e1rio.<\/p>\n<p align=\"left\">Publique-se.<\/p>\n<p style=\"text-align: left;\" align=\"center\">Vit\u00f3ria, 03 de outubro de 2019.<\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\">Des. S\u00c9RGIO LUIZ TEIXEIRA GAMA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ESTADO DO ESP\u00cdRITO SANTO \u2013 PODER JUDICI\u00c1RIO TRIBUNAL DE JUSTI\u00c7A PRESID\u00caNCIA &nbsp; Ato Normativo N\u00ba 135\/2019 Altera parcialmente os Atos Normativos n\u00b0s 118\/2019 e 132\/2019, que institu\u00edram e convocaram a equipe de trabalho que atuar\u00e1 na Pauta Concentrada de Media\u00e7\u00e3o em Cachoeiro de Itapemirim. O Excelent\u00edssimo Senhor Desembargador S\u00c9RGIO LUIZ TEIXEIRA GAMA, Presidente do Egr\u00e9gio [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,14],"tags":[],"_links":{"self":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/28110"}],"collection":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/comments?post=28110"}],"version-history":[{"count":3,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/28110\/revisions"}],"predecessor-version":[{"id":28115,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/28110\/revisions\/28115"}],"wp:attachment":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/media?parent=28110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/categories?post=28110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/tags?post=28110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}