{"id":31216,"date":"2021-03-10T13:14:37","date_gmt":"2021-03-10T16:14:37","guid":{"rendered":"https:\/\/www.tjes.jus.br\/corregedoria\/?p=31216"},"modified":"2021-03-10T13:22:42","modified_gmt":"2021-03-10T16:22:42","slug":"oficio-circular-no-0681700-2021-disp-02-03-2021","status":"publish","type":"post","link":"https:\/\/www.tjes.jus.br\/corregedoria\/2021\/03\/10\/oficio-circular-no-0681700-2021-disp-02-03-2021\/","title":{"rendered":"OF\u00cdCIO-CIRCULAR N\u00ba 0681700\/2021 \u2013 DISP. 02\/03\/2021 &#8211; REPUBLICA\u00c7\u00c3O"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>OF\u00cdCIO CIRCULAR CGJES\u00a00681700\/7000841-42.2021.8.08.0000<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>O Excelent\u00edssimo Senhor Desembargador\u00a0<strong>NEY BATISTA COUTINHO<\/strong>, Corregedor Geral da Justi\u00e7a do Estado do Esp\u00edrito Santo, no uso de suas atribui\u00e7\u00f5es legais e,<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO\u00a0<\/strong>que a Corregedoria Geral da Justi\u00e7a \u00e9 \u00f3rg\u00e3o de fiscaliza\u00e7\u00e3o, que disciplina a orienta\u00e7\u00e3o administrativa, com jurisdi\u00e7\u00e3o em todo Estado, conforme disp\u00f5e o artigo\u00a035, da Lei Complementar Estadual n\u00ba. 234\/2002, o artigo\u00a037, da Lei Federal n\u00ba. 8.935\/94 (Lei dos Not\u00e1rios e Registradores) e o\u00a0artigo\u00a08\u00ba, do C\u00f3digo de Normas;<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong>\u00a0o que restou decidido nos autos da Argui\u00e7\u00e3o de Descumprimento de Preceito Fundamental n\u00ba 569\/DF, que\u00a0concedeu medida cautelar para determinar que\u00a0valores ou bens provenientes dos efeitos da condena\u00e7\u00e3o criminal, colabora\u00e7\u00e3o premiada ou outros acordos observem os estritos termos do artigo 91, do C\u00f3digo Penal, do\u00a0inciso IV do artigo\u00a04\u00ba, da Lei n\u00ba. 12.850\/13 e do inciso I, do artigo\u00a07\u00ba, da Lei n\u00ba. 9.613\/98;<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong>\u00a0que na supradita ADPF n\u00ba 569\/DF, vedou-se que os mencionados montantes auferidos pela condena\u00e7\u00e3o criminal, colabora\u00e7\u00f5es premiadas ou outros acordos sejam distribu\u00eddos de maneira vinculada, estabelecida ou determinada pelo Minist\u00e9rio P\u00fablico, por termos do mencionado acordo firmado entre este e o respons\u00e1vel pagador, ou por determina\u00e7\u00e3o do \u00f3rg\u00e3o jurisdicional em que tramitam esses procedimentos;<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO,<\/strong>\u00a0por fim, os termos do\u00a0Of\u00edcio-Circular n\u00ba 4\/2021 de autoria do Ministro Alexandre de Moraes, relator da ADPF\u00a0n\u00ba 569\/DF no e. Supremo Tribunal Federal;<\/p>\n<p style=\"text-align: justify;\"><strong>RESOLVE:<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>DAR CI\u00caNCIA<\/strong>\u00a0a todos os magistrados(as) do Estado do Esp\u00edrito Santo do inteiro teor da decis\u00e3o do Ministro Alexandre de Moraes nos autos da\u00a0Argui\u00e7\u00e3o de Descumprimento de Preceito Fundamental n\u00ba 569\/DF, bem como do Of\u00edcio-Circular STF n\u00ba 4\/2021.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>PUBLIQUE-SE.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">Vit\u00f3ria\/ES, 18 de fevereiro de 2021.<\/p>\n<p style=\"text-align: center;\"><strong>Corregedor Geral da Justi\u00e7a<\/strong><\/p>\n<p style=\"text-align: center;\"><strong><a href=\"https:\/\/sistemas.tjes.jus.br\/ediario\/images\/OF%C3%8DCIO_CIRCULAR_STF_N%C2%BA_04-2021_copia.pdf\" target=\"_blank\" rel=\"noopener\">Of\u00edcio-Circular STF n\u00ba 4\/2021 e Decis\u00e3o<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>OF\u00cdCIO CIRCULAR CGJES\u00a00681700\/7000841-42.2021.8.08.0000 &nbsp; O Excelent\u00edssimo Senhor Desembargador\u00a0NEY BATISTA COUTINHO, Corregedor Geral da Justi\u00e7a do Estado do Esp\u00edrito Santo, no uso de suas atribui\u00e7\u00f5es legais e, &nbsp; CONSIDERANDO\u00a0que a Corregedoria Geral da Justi\u00e7a \u00e9 \u00f3rg\u00e3o de fiscaliza\u00e7\u00e3o, que disciplina a orienta\u00e7\u00e3o administrativa, com jurisdi\u00e7\u00e3o em todo Estado, conforme disp\u00f5e o artigo\u00a035, da Lei Complementar Estadual [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/31216"}],"collection":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/comments?post=31216"}],"version-history":[{"count":2,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/31216\/revisions"}],"predecessor-version":[{"id":31220,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/31216\/revisions\/31220"}],"wp:attachment":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/media?parent=31216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/categories?post=31216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/tags?post=31216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}