{"id":31271,"date":"2021-03-10T16:12:37","date_gmt":"2021-03-10T19:12:37","guid":{"rendered":"https:\/\/www.tjes.jus.br\/corregedoria\/?p=31271"},"modified":"2021-03-11T13:44:16","modified_gmt":"2021-03-11T16:44:16","slug":"oficio-circular-no-17-2021-disp-05-03-2021","status":"publish","type":"post","link":"https:\/\/www.tjes.jus.br\/corregedoria\/2021\/03\/10\/oficio-circular-no-17-2021-disp-05-03-2021\/","title":{"rendered":"OF\u00cdCIO-CIRCULAR N\u00ba 17\/2021 &#8211; DISP. 05\/03\/2021"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>OF\u00cdCIO-CIRCULAR N\u00ba 17\/2021 &#8211; SECAO DE MONITORAMENTO DE FORO EXTRAJUDICIAL<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Vit\u00f3ria, 03 de mar\u00e7o de 2021.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">A Coordenadora de Monitoramento de Foro Judicial e Extrajudicial da Eg. Corregedoria Geral da Justi\u00e7a do Estado do Esp\u00edrito Santo, no uso de suas atribui\u00e7\u00f5es legais:<\/p>\n<p style=\"text-align: justify;\" align=\"justify\"><strong>CONSIDERANDO<\/strong>\u00a0que a Corregedoria Geral da Justi\u00e7a \u00e9 \u00f3rg\u00e3o de fiscaliza\u00e7\u00e3o, disciplina e orienta\u00e7\u00e3o administrativa, com circunscri\u00e7\u00e3o em todo o Estado, conforme art. 35 da Lei Complementar Estadual n.\u00ba 234\/2002 (COJES);<\/p>\n<p style=\"text-align: justify;\" align=\"justify\"><strong>CONSIDERANDO<\/strong>\u00a0o disposto no Provimento n\u00ba 31\/2019, desta Corregedoria Geral da Justi\u00e7a, que delegou a\u00a0Coordenadora\u00a0de Monitoramento de Foro Judicial e Extrajudicial a proceder, de of\u00edcio,\u00a0a publica\u00e7\u00e3o de Of\u00edcio-Circular\u00a0acerca da inutiliza\u00e7\u00e3o dos pap\u00e9is de seguran\u00e7a\u00a0noticiada\u00a0pelas autoridades apostilantes por meio de certid\u00e3o,\u00a0a fim de que seja dada\u00a0ampla publicidade.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\"><strong>CONSIDERANDO<\/strong>\u00a0o recebimento do comunicado enviado a esta Corregedoria por meio do Malote digital com c\u00f3digo de rastreabilidade n.\u00ba\u00a080820201670949<strong>,<\/strong>\u00a0do\u00a0<strong>Cart\u00f3rio de Registro Civil e Tabelionato da Sede\u00a0da Comarca de Linhares\/ES<\/strong>\u00a0(documento SEI n\u00ba 0698518);<\/p>\n<p align=\"justify\"><strong>CONSIDERANDO<\/strong>\u00a0que o referido comunicado informa sobre a inutiliza\u00e7\u00e3o de pap\u00e9is de seguran\u00e7a para o ato de aposi\u00e7\u00e3o de apostila, conforme consta em anexo.<\/p>\n<p align=\"justify\"><strong>RECOMENDA<\/strong>\u00a0aos Ju\u00edzes de Direito Diretores dos Foros, Membros do Minist\u00e9rio P\u00fablico, Advogados, Not\u00e1rios e Registradores, Serventu\u00e1rios e a quem mais possa interessar, que observem os comunicados em anexo e adotem as provid\u00eancias que entenderem pertinentes.<\/p>\n<p align=\"justify\"><strong>Publique-se.<\/strong><\/p>\n<p align=\"center\"><strong>Coordenadora de Monitoramento de Foro Judicial e Extrajudicial<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><strong><a href=\"https:\/\/sistemas.tjes.jus.br\/ediario\/images\/80820201670949___RCT_DA_SEDE___LINHARES.pdf\" target=\"_blank\" rel=\"noopener\">Anexo &#8211; Clique aqui<\/a><\/strong><\/p>\n<p style=\"text-align: center;\" align=\"center\">\n","protected":false},"excerpt":{"rendered":"<p>OF\u00cdCIO-CIRCULAR N\u00ba 17\/2021 &#8211; SECAO DE MONITORAMENTO DE FORO EXTRAJUDICIAL &nbsp; Vit\u00f3ria, 03 de mar\u00e7o de 2021. A Coordenadora de Monitoramento de Foro Judicial e Extrajudicial da Eg. Corregedoria Geral da Justi\u00e7a do Estado do Esp\u00edrito Santo, no uso de suas atribui\u00e7\u00f5es legais: CONSIDERANDO\u00a0que a Corregedoria Geral da Justi\u00e7a \u00e9 \u00f3rg\u00e3o de fiscaliza\u00e7\u00e3o, disciplina e [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/31271"}],"collection":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/comments?post=31271"}],"version-history":[{"count":3,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/31271\/revisions"}],"predecessor-version":[{"id":31284,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/31271\/revisions\/31284"}],"wp:attachment":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/media?parent=31271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/categories?post=31271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/tags?post=31271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}