{"id":31300,"date":"2021-03-15T14:34:18","date_gmt":"2021-03-15T17:34:18","guid":{"rendered":"https:\/\/www.tjes.jus.br\/corregedoria\/?p=31300"},"modified":"2021-03-15T14:37:13","modified_gmt":"2021-03-15T17:37:13","slug":"oficio-circular-cgjes-0704471-2021-disponibilizado-em-15-03-2021","status":"publish","type":"post","link":"https:\/\/www.tjes.jus.br\/corregedoria\/2021\/03\/15\/oficio-circular-cgjes-0704471-2021-disponibilizado-em-15-03-2021\/","title":{"rendered":"OF\u00cdCIO CIRCULAR CGJES 0704471\/2021 \u2013 DISP. 15\/03\/2021"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>OF\u00cdCIO CIRCULAR CGJES\u00a00704471\/7001425-12.2021.8.08.0000<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">O Exmo. Sr. Desembargador Corregedor-Geral da Justi\u00e7a do Estado do Esp\u00edrito Santo, no uso de suas atribui\u00e7\u00f5es legais e,<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong>\u00a0que a Corregedoria Geral da Justi\u00e7a \u00e9 \u00f3rg\u00e3o de fiscaliza\u00e7\u00e3o, disciplina e orienta\u00e7\u00e3o administrativa, com circunscri\u00e7\u00e3o em todo o Estado, conforme art. 35 da Lei Complementar Estadual n.\u00ba 234\/2002 (COJES);<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong>\u00a0o recebimento do comunicado enviado a esta Corregedoria por meio do Malote digital com c\u00f3digo de rastreabilidade n.\u00ba\u00a0<strong>81420201284102<\/strong><strong>\u200b<\/strong><strong>,<\/strong>\u00a0da Corregedoria Geral de Justi\u00e7a do Estado do Par\u00e1\u00a0(Documento SEI n\u00ba 0704437);<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong>\u00a0que o referido comunicado informa sobre a inutiliza\u00e7\u00e3o de pap\u00e9is de seguran\u00e7a para o ato de aposi\u00e7\u00e3o de apostila no\u00a0<strong>Cart\u00f3rio do 4\u00ba Of\u00edcio de Notas de Bel\u00e9m\/PA<\/strong>, conforme consta em anexo.<\/p>\n<p style=\"text-align: justify;\"><strong>RECOMENDA<\/strong>\u00a0aos Ju\u00edzes de Direito Diretores dos Foros, Membros do Minist\u00e9rio P\u00fablico, Advogados, Not\u00e1rios e Registradores, Serventu\u00e1rios e a quem mais possa interessar, que observem os comunicados em anexo e adotem as provid\u00eancias que entenderem pertinentes.<\/p>\n<p style=\"text-align: justify;\"><strong>Publique-se.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">Vit\u00f3ria\/ES, 08 de mar\u00e7o de 2021.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong>DESEMBARGADOR\u00a0NEY BATISTA COUTINHO<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Corregedor Geral da Justi\u00e7a<\/strong><\/p>\n<p style=\"text-align: center;\"><strong><a href=\"https:\/\/sistemas.tjes.jus.br\/ediario\/images\/81420201284102___4__DE_NOTAS_DE_BELEM.pdf\" target=\"_blank\" rel=\"noopener\">Anexo &#8211; Clique aqui<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>OF\u00cdCIO CIRCULAR CGJES\u00a00704471\/7001425-12.2021.8.08.0000 &nbsp; O Exmo. Sr. Desembargador Corregedor-Geral da Justi\u00e7a do Estado do Esp\u00edrito Santo, no uso de suas atribui\u00e7\u00f5es legais e, CONSIDERANDO\u00a0que a Corregedoria Geral da Justi\u00e7a \u00e9 \u00f3rg\u00e3o de fiscaliza\u00e7\u00e3o, disciplina e orienta\u00e7\u00e3o administrativa, com circunscri\u00e7\u00e3o em todo o Estado, conforme art. 35 da Lei Complementar Estadual n.\u00ba 234\/2002 (COJES); CONSIDERANDO\u00a0o recebimento [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/31300"}],"collection":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/comments?post=31300"}],"version-history":[{"count":4,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/31300\/revisions"}],"predecessor-version":[{"id":31306,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/31300\/revisions\/31306"}],"wp:attachment":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/media?parent=31300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/categories?post=31300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/tags?post=31300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}