{"id":31599,"date":"2021-04-26T13:30:13","date_gmt":"2021-04-26T16:30:13","guid":{"rendered":"https:\/\/www.tjes.jus.br\/corregedoria\/?p=31599"},"modified":"2024-05-15T15:45:47","modified_gmt":"2024-05-15T18:45:47","slug":"resolucao-no-008-2021-disp-26-04-2021","status":"publish","type":"post","link":"https:\/\/www.tjes.jus.br\/corregedoria\/2021\/04\/26\/resolucao-no-008-2021-disp-26-04-2021\/","title":{"rendered":"RESOLU\u00c7\u00c3O N\u00ba 008\/2021 \u2013 DISP. 26\/04\/2021 &#8211; REVOGADO"},"content":{"rendered":"<h3 align=\"center\"><span style=\"color: #ff0000;\"><strong>REVOGADO PELA <a href=\"https:\/\/www.tjes.jus.br\/corregedoria\/2024\/05\/15\/resolucao-no-066-2024-disp-13-05-2024\/\">RESOLU\u00c7\u00c3O 066\/2024<\/a> DISP. 13\/05\/2024<\/strong><\/span><\/h3>\n<p style=\"text-align: center;\"><del>PODER JUDICI\u00c1RIO DO ESTADO DO ESP\u00cdRITO SANTO &#8211; PJES<\/del><\/p>\n<p style=\"text-align: center;\"><del>RUA DESEMBARGADOR HOMERO MAFRA,60 &#8211; Bairro ENSEADA DO SU\u00c1 &#8211; CEP 29050906 &#8211; Vit\u00f3ria &#8211; ES &#8211; www.tjes.jus.br<\/del><\/p>\n<p style=\"text-align: center;\"><del><strong>RESOLU\u00c7\u00c3O N\u00ba 008\/2021<\/strong><\/del><\/p>\n<p style=\"text-align: center;\"><del><strong>\u00a0<\/strong><\/del><\/p>\n<p><del><em>Regulamenta o procedimento de consigna\u00e7\u00e3o em folha de pagamento\u00a0<\/em><em>no \u00e2mbito do Poder Judici\u00e1rio do Estado do Esp\u00edrito Santo<\/em>.<\/del><\/p>\n<p><del>O Presidente do Egr\u00e9gio Tribunal de Justi\u00e7a do Estado do Esp\u00edrito Santo, no uso de suas atribui\u00e7\u00f5es legais e regimentais e, conforme decis\u00e3o do Egr\u00e9gio Tribunal Pleno, em sess\u00e3o administrativa do Tribunal Pleno, realizada no dia 22 de abril de 2021.<\/del><\/p>\n<p><del><strong>CONSIDERANDO<\/strong>\u00a0a necessidade de regulamentar o art. 74 da Lei Complementar n\u00ba 46\/1994;<\/del><\/p>\n<p><del><strong>CONSIDERANDO<\/strong>\u00a0a necessidade de padroniza\u00e7\u00e3o e atualiza\u00e7\u00e3o do procedimento de solicita\u00e7\u00e3o e controle dos processos de consigna\u00e7\u00e3o em folhas de pagamento processadas pelo Poder Judici\u00e1rio do Estado do Esp\u00edrito Santo referente a Magistrados e de Servidores.<\/del><\/p>\n<p><del><strong>CONSIDERANDO<\/strong>\u00a0o dever de atua\u00e7\u00e3o pautado pelos princ\u00edpios constitucionais da isonomia, legalidade, impessoalidade, moralidade, publicidade, efici\u00eancia, da livre iniciativa e livre concorr\u00eancia;<\/del><\/p>\n<p><del><strong>CONSIDERANDO<\/strong>\u00a0a necessidade de estabelecer maior seguran\u00e7a e facilidade nas contrata\u00e7\u00f5es;<\/del><\/p>\n<p><del><strong>CONSIDERANDO<\/strong>\u00a0a possibilidade de obten\u00e7\u00e3o de uma menor taxa, alongamento e\/ou negocia\u00e7\u00e3o de contrato de empr\u00e9stimo consignado, com benef\u00edcios diretos no aproveitamento da margem consign\u00e1vel;<\/del><\/p>\n<p><del><strong>CONSIDERANDO<\/strong>\u00a0a possibilidade de minimizar o impacto das d\u00edvidas no or\u00e7amento pessoal do consignado, com a redu\u00e7\u00e3o do custo do endividamento e satisfa\u00e7\u00e3o pessoal;<\/del><\/p>\n<p><del><strong>CONSIDERANDO<\/strong>\u00a0a utiliza\u00e7\u00e3o do Sistema Digital de Consigna\u00e7\u00f5es como plataforma institucional de gest\u00e3o de consignados e a demanda consolidada de averba\u00e7\u00f5es de consigna\u00e7\u00f5es em folhas de pagamento processadas pelo Poder Judici\u00e1rio do Estado do Esp\u00edrito Santo referente a Magistrados e a Servidores;<\/del><\/p>\n<p><del><strong>CONSIDERANDO<\/strong>\u00a0a necessidade de estabelecer maior seguran\u00e7a, facilidade e proteger os consignados de eventuais fraudes no processo de contrata\u00e7\u00e3o de consignados;<\/del><\/p>\n<p><del><strong>RESOLVE:<\/strong><\/del><\/p>\n<p><del>Regulamentar o procedimento administrativo de consigna\u00e7\u00e3o em folhas de pagamento processadas pelo Poder Judici\u00e1rio do Estado do Esp\u00edrito Santo referente a Magistrados e a Servidores, nos seguintes termos.<\/del><\/p>\n<p><del>Art. 1\u00ba Os procedimentos para consigna\u00e7\u00e3o em folhas de pagamento processadas pelo Poder Judici\u00e1rio do Estado do Esp\u00edrito Santo referente a Magistrados e a Servidores dever\u00e3o observar as normas contidas nesta Resolu\u00e7\u00e3o.<\/del><\/p>\n<p><del>Art. 2\u00ba Para fins desta Resolu\u00e7\u00e3o considera-se:<\/del><\/p>\n<p><del>I &#8211; consignante: Poder Judici\u00e1rio do Estado do Esp\u00edrito Santo;<\/del><\/p>\n<p><del>II &#8211; consignado: Magistrado ou Servidor cujas folhas de pagamento s\u00e3o processadas pelo Poder Judici\u00e1rio do Estado do Esp\u00edrito Santo e que autorize desconto de consigna\u00e7\u00f5es em folha de pagamento;<\/del><\/p>\n<p><del>III &#8211; consignat\u00e1ria: institui\u00e7\u00e3o destinat\u00e1ria dos cr\u00e9ditos resultantes das consigna\u00e7\u00f5es;<\/del><\/p>\n<p><del>IV &#8211; consigna\u00e7\u00e3o obrigat\u00f3ria: desconto em folha de pagamento efetuado por for\u00e7a de lei ou decis\u00e3o judicial;<\/del><\/p>\n<p><del>V &#8211; consigna\u00e7\u00e3o facultativa: desconto autorizado pelo consignado, em folha de pagamento;<\/del><\/p>\n<p><del>VI &#8211; consigna\u00e7\u00e3o obrigat\u00f3ria representativa: \u00e9 o desconto em folha de pagamento, de natureza contributiva, devido pelo consignado em raz\u00e3o de filia\u00e7\u00e3o onerosa a entidades sindicais, cooperativas ou a associa\u00e7\u00f5es representativas de classe de magistrados e\/ou de servidores p\u00fablicos do Poder Judici\u00e1rio, mesmo que n\u00e3o exclusivas, ou de sa\u00fade;<\/del><\/p>\n<p><del>VII &#8211; consigna\u00e7\u00e3o facultativa por prazo indeterminado: \u00e9 o desconto facultativo em folha de pagamento, de natureza contratual, autorizado pelo consignado por per\u00edodo indeterminado;<\/del><\/p>\n<p><del>VIII &#8211; consigna\u00e7\u00e3o facultativa por prazo determinado: \u00e9 o desconto facultativo em folha de pagamento, de natureza contratual, autorizado pelo consignado por per\u00edodo determinado;<\/del><\/p>\n<p><del>IX &#8211; consigna\u00e7\u00e3o facultativa de longo prazo: \u00e9 o desconto facultativo em folha de pagamento, de natureza contratual, autorizado pelo consignado por longo prazo;<\/del><\/p>\n<p><del>X &#8211; sistema digital de consigna\u00e7\u00f5es: sistema informatizado que suporta o processo de gest\u00e3o de margem consign\u00e1vel e a manuten\u00e7\u00e3o online de contratos consignados, via internet;<\/del><\/p>\n<p><del>XI &#8211; associa\u00e7\u00e3o representativa de classe: \u00e9 aquela cuja filia\u00e7\u00e3o seja permitida, mesmo que n\u00e3o exclusiva, a magistrados e\/ou a servidores p\u00fablicos do Poder Judici\u00e1rio;<\/del><\/p>\n<p><del>XII &#8211; remunera\u00e7\u00e3o \u00e9 a soma do vencimento ou do subs\u00eddio com os adicionais de car\u00e1ter individual e demais vantagens permanentes, nestas compreendidas as relativas \u00e0 natureza ou ao local de trabalho.<\/del><\/p>\n<p><del>XIII &#8211; margem consign\u00e1vel: parcela da remunera\u00e7\u00e3o pass\u00edvel de consigna\u00e7\u00e3o em folha de pagamento.<\/del><\/p>\n<p><del>Art. 3\u00ba S\u00e3o consideradas consigna\u00e7\u00f5es obrigat\u00f3rias:<\/del><\/p>\n<p><del>I &#8211; contribui\u00e7\u00e3o previdenci\u00e1ria obrigat\u00f3ria ao Regime Geral de Previd\u00eancia Social ou ao Regime Pr\u00f3prio de Previd\u00eancia;<\/del><\/p>\n<p><del>II &#8211; contribui\u00e7\u00e3o para Previd\u00eancia Complementar Estadual &#8211; PREVES, no que se referir ao valor correspondente \u00e0 contrapartida patronal;<\/del><\/p>\n<p><del>III &#8211; imposto de renda retido na fonte;<\/del><\/p>\n<p><del>IV &#8211; pens\u00e3o aliment\u00edcia judicial;<\/del><\/p>\n<p><del>V &#8211; descontos autorizados por medida judicial;<\/del><\/p>\n<p><del>VI &#8211; restitui\u00e7\u00f5es e indeniza\u00e7\u00f5es devidas ao er\u00e1rio;<\/del><\/p>\n<p><del>VII &#8211; contribui\u00e7\u00e3o sindical;<\/del><\/p>\n<p><del>VIII &#8211; outros descontos determinados por lei ou por decis\u00e3o judicial ou administrativa.<\/del><\/p>\n<p><del>Art. 4\u00ba Considera-se consigna\u00e7\u00e3o obrigat\u00f3ria representativa a contribui\u00e7\u00e3o mensal destinada a entidade sindical, ou associa\u00e7\u00e3o representativa de classe, ou cooperativa, decorrente de filia\u00e7\u00e3o onerosa.<\/del><\/p>\n<p><del>Art. 5\u00ba Considera-se consigna\u00e7\u00e3o facultativa especial \/ plano de sa\u00fade titular o plano de sa\u00fade do titular relativo a Magistrado ou Servidor cujas folhas de pagamento s\u00e3o processadas pelo Poder Judici\u00e1rio do Estado do Esp\u00edrito Santo, de acordo com Recomenda\u00e7\u00e3o CNJ n\u00ba 84\/2020.<\/del><\/p>\n<p><del>Art. 6\u00ba S\u00e3o consideradas consigna\u00e7\u00f5es facultativas por prazo indeterminado:<\/del><\/p>\n<p><del>I &#8211; pens\u00e3o aliment\u00edcia volunt\u00e1ria, consignada em favor de dependente que conste dos assentamentos funcionais do consignado;<\/del><\/p>\n<p><del>II &#8211; plano de sa\u00fade de dependentes;<\/del><\/p>\n<p><del>III &#8211; pr\u00eamio de seguro;<\/del><\/p>\n<p><del>IV &#8211; plano odontol\u00f3gico;<\/del><\/p>\n<p><del>V &#8211; previd\u00eancia complementar, inclusive a Previd\u00eancia Complementar Estadual &#8211; PREVES, no que exceder a contrapartida patronal;<\/del><\/p>\n<p><del>VI &#8211; plano de montepio e pec\u00falio;<\/del><\/p>\n<p><del>VII &#8211; capitaliza\u00e7\u00e3o, exceto as previstas no art\u00ba 1\u00ba, VI;<\/del><\/p>\n<p><del>VIII &#8211; telefonia;<\/del><\/p>\n<p><del>IX &#8211; poupan\u00e7a;<\/del><\/p>\n<p><del>X &#8211; diversos.<\/del><\/p>\n<p><del>Art. 7\u00ba S\u00e3o consideradas consigna\u00e7\u00f5es facultativas por prazo determinado:<\/del><\/p>\n<p><del>I &#8211; empr\u00e9stimo pessoal;<\/del><\/p>\n<p><del>II &#8211; parcela de cons\u00f3rcio;<\/del><\/p>\n<p><del>III &#8211; plano de sa\u00fade com prazo;<\/del><\/p>\n<p><del>IV &#8211; farm\u00e1cia;<\/del><\/p>\n<p><del>V &#8211; poupan\u00e7a com prazo;<\/del><\/p>\n<p><del>VI &#8211; diversos, com prazo.<\/del><\/p>\n<p><del>Art. 8\u00ba \u00c9 considerada consigna\u00e7\u00e3o facultativa de longo prazo o financiamento habitacional, concedido \u00fanico e exclusivamente pelas institui\u00e7\u00f5es financeiras credenciadas para esta finalidade.<\/del><\/p>\n<p><del>Par\u00e1grafo \u00fanico. As opera\u00e7\u00f5es de financiamento habitacional previsto no caput deste artigo poder\u00e3o ser registradas no Sistema Digital de Consigna\u00e7\u00f5es por associa\u00e7\u00e3o representativa de classe, desde que devidamente credenciada pela institui\u00e7\u00e3o financeira operadora de financiamento habitacional e pelo Secret\u00e1rio Geral.<\/del><\/p>\n<p><del>Art. 9\u00ba O credenciamento para operar com consigna\u00e7\u00e3o junto ao Poder Judici\u00e1rio do Estado do Esp\u00edrito Santo ser\u00e1 \u00fanico para cada institui\u00e7\u00e3o, independentemente do n\u00famero de esp\u00e9cies de consigna\u00e7\u00e3o pretendidas no pedido a que se refere o art. 13 desta Resolu\u00e7\u00e3o.<\/del><\/p>\n<p><del>\u00a71\u00ba Somente ser\u00e1 concedido credenciamento nas esp\u00e9cies em que a consignat\u00e1ria estiver autorizada a operar por lei ou por estatuto.<\/del><\/p>\n<p><del>\u00a72\u00ba No credenciamento de esp\u00e9cies de consigna\u00e7\u00f5es que necessitem de autoriza\u00e7\u00e3o de \u00f3rg\u00e3o regulador e fiscalizador observar-se-\u00e1 a legisla\u00e7\u00e3o pr\u00f3pria dos \u00f3rg\u00e3os.<\/del><\/p>\n<p><del>\u00a73\u00ba No credenciamento da esp\u00e9cie contribui\u00e7\u00e3o associativa ou an\u00e1loga observar-se-\u00e3o as disposi\u00e7\u00f5es estatut\u00e1rias.<\/del><\/p>\n<p><del>Art. 10\u00ba A soma das consigna\u00e7\u00f5es facultativas e compuls\u00f3rias obrigat\u00f3rias n\u00e3o poder\u00e1 ultrapassar 70% (setenta por cento) da remunera\u00e7\u00e3o habitual do servidor ou do magistrado, inclusive as vantagens permanentes.<\/del><\/p>\n<p><del>\u00a71\u00ba A soma das consigna\u00e7\u00f5es facultativas por prazo determinado e por prazo indeterminado, previstas nos artigos 6\u00ba e 7\u00ba desta Resolu\u00e7\u00e3o, n\u00e3o poder\u00e1 ultrapassar 35% (trinta e cinco por cento) da remunera\u00e7\u00e3o habitual do servidor ou magistrado, inclusive as vantagens permanentes.<\/del><\/p>\n<p><del>I &#8211; N\u00e3o se inclui no \u00a71\u00ba a consigna\u00e7\u00e3o facultativa por tempo indeterminado especial \/ Plano de sa\u00fade do titular, conforme Recomenda\u00e7\u00e3o CNJ n\u00ba 84\/2020.<\/del><\/p>\n<p><del>\u00a72\u00ba Na hip\u00f3tese de as somas estabelecidas no caput ou no \u00a71\u00ba ultrapassarem os percentuais indicados, ser\u00e1 procedida a suspens\u00e3o do desconto em folha de pagamento, de parte ou do total das consigna\u00e7\u00f5es, conforme a necessidade, para que o total de valores debitados no m\u00eas n\u00e3o exceda o limite.<\/del><\/p>\n<p><del>\u00a73\u00ba A suspens\u00e3o referida no \u00a72\u00ba ser\u00e1 realizada independentemente da data de inclus\u00e3o da consigna\u00e7\u00e3o, respeitada a ordem de prioridade estabelecida no art.11.<\/del><\/p>\n<p><del>\u00a74\u00ba A suspens\u00e3o abranger\u00e1 sempre o valor integral da consigna\u00e7\u00e3o.<\/del><\/p>\n<p><del>\u00a75\u00ba A consigna\u00e7\u00e3o facultativa especial \/ plano de sa\u00fade titular n\u00e3o ser\u00e1 computada para fins de apura\u00e7\u00e3o do limite do \u00a71\u00ba no Sistema Digital de Consigna\u00e7\u00f5es do Poder Judici\u00e1rio do Estado do Esp\u00edrito Santo, de acordo com o art. 1\u00ba da Recomenda\u00e7\u00e3o n\u00ba 84, de 16 de dezembro de 2020, do Conselho Nacional de Justi\u00e7a &#8211; CNJ.<\/del><\/p>\n<p><del>\u00a76\u00ba N\u00e3o ser\u00e1 autorizado lan\u00e7amento de cr\u00e9dito consignado.<\/del><\/p>\n<p><del>\u00a77\u00ba Servidores inativos do Poder Judici\u00e1rio do Estado do Esp\u00edrito Santo que recebem aux\u00edlio sa\u00fade em folha de pagamento processada pelo PJES, ter\u00e3o, \u00fanica e exclusivamente nesta folha, consigna\u00e7\u00e3o da modalidade consigna\u00e7\u00e3o facultativa especial \/ plano de sa\u00fade titular.<\/del><\/p>\n<p><del>\u00a78\u00ba A consigna\u00e7\u00e3o tratada no par\u00e1grafo anterior n\u00e3o se sujeita aos limites estabelecidos no art. 10 \u00a7 1\u00ba.<\/del><\/p>\n<p><del>Art. 11. As consigna\u00e7\u00f5es ter\u00e3o prioridade de descontos, na seguinte ordem:<\/del><\/p>\n<p><del>I &#8211; obrigat\u00f3ria;<\/del><\/p>\n<p><del>II &#8211; facultativa especial \/ plano de sa\u00fade titular;<\/del><\/p>\n<p><del>III &#8211; facultativas por prazo indeterminado;<\/del><\/p>\n<p><del>IV &#8211; facultativas de longo prazo;<\/del><\/p>\n<p><del>V &#8211; facultativas por prazo determinado.<\/del><\/p>\n<p><del>\u00a71\u00ba Havendo necessidade de aplicar prioridade dentro da classe facultativa por prazo indeterminado, prevalecer\u00e1 a consigna\u00e7\u00e3o na ordem crescente dos incisos do art. 6\u00ba desta Resolu\u00e7\u00e3o.<\/del><\/p>\n<p><del>\u00a72\u00ba Havendo necessidade de aplicar prioridade dentro da classe facultativa por prazo determinado, prevalecer\u00e1 a consigna\u00e7\u00e3o contratada h\u00e1 mais tempo.<\/del><\/p>\n<p><del>\u00a73\u00ba A consigna\u00e7\u00e3o facultativa de longo prazo, prevista no art. 8\u00ba, tem como prazo m\u00e1ximo o limite de 360 (trezentos e sessenta) parcelas mensais.<\/del><\/p>\n<p><del>\u00a74\u00ba A consigna\u00e7\u00e3o facultativa por prazo determinado, prevista no art. 7\u00ba, tem como prazo m\u00e1ximo o limite de 96 (noventa e seis) parcelas mensais.<\/del><\/p>\n<p><del>Art. 12. \u00c9 de compet\u00eancia do Secret\u00e1rio Geral, por meio de termo de contrato, o credenciamento e descredenciamento de consignat\u00e1ria para operar as consigna\u00e7\u00f5es previstas nos artigos 4\u00ba, 5\u00ba, 6\u00ba, 7\u00ba e 8\u00ba, no Poder Judici\u00e1rio do Estado do Esp\u00edrito Santo.<\/del><\/p>\n<p><del>Art. 13. O pedido de credenciamento dever\u00e1 ser dirigido ao Secret\u00e1rio Geral, na forma de requerimento, indicando quais as esp\u00e9cies de consigna\u00e7\u00f5es pretendidas, acompanhado dos seguintes documentos:<\/del><\/p>\n<p><del>I &#8211; prova de inscri\u00e7\u00e3o, relativa ao domic\u00edlio ou sede do credenciado, pertinente ao seu ramo de atividade e compat\u00edvel com o objeto do credenciamento, no que couber:<\/del><\/p>\n<p><del>a) no Cadastro Nacional de Pessoa Jur\u00eddica &#8211; CNPJ;<\/del><\/p>\n<p><del>b) no Cadastro de contribuintes estadual (Inscri\u00e7\u00e3o Estadual);<\/del><\/p>\n<p><del>c) no Cadastro de contribuintes municipal (Inscri\u00e7\u00e3o Municipal).<\/del><\/p>\n<p><del>II &#8211; c\u00e9dula de identidade do representante legal da institui\u00e7\u00e3o;<\/del><\/p>\n<p><del>III &#8211; ato constitutivo, estatuto ou contrato social em vigor, devidamente registrado, em se tratando de sociedades comerciais, e, no caso de sociedades por a\u00e7\u00f5es, acompanhado de documentos de elei\u00e7\u00e3o de seus administradores;<\/del><\/p>\n<p><del>IV &#8211; inscri\u00e7\u00e3o do ato constitutivo, no caso de sociedades civis, acompanhada de prova de diretoria em exerc\u00edcio;<\/del><\/p>\n<p><del>V &#8211; decreto de autoriza\u00e7\u00e3o, em se tratando de empresa ou sociedade estrangeira em funcionamento no Pa\u00eds, e ato de registro ou autoriza\u00e7\u00e3o para funcionamento expedido pelo \u00f3rg\u00e3o competente, quando a atividade assim exigir;<\/del><\/p>\n<p><del>VI &#8211; lei, ato constitutivo ou autorizativo, tratando-se de institui\u00e7\u00e3o, \u00f3rg\u00e3o ou entidade p\u00fablica, de qualquer esfera de Governo;<\/del><\/p>\n<p><del>VII &#8211; prova de regularidade para com a Fazenda Federal, com a Fazenda Estadual e com a Fazenda Municipal do domic\u00edlio ou sede da institui\u00e7\u00e3o, ou outra equivalente, na forma da lei:<\/del><\/p>\n<p><del>a) Certid\u00e3o de D\u00e9bitos Relativos a Cr\u00e9ditos Tribut\u00e1rios Federais e \u00e0 D\u00edvida Ativa da Uni\u00e3o (Secretaria da Receita Federal \/ Procuradoria-Geral da Fazenda Nacional);<\/del><\/p>\n<p><del>b) Certid\u00e3o Negativa de D\u00e9bito (Secretaria de Estado da Fazenda &#8211; SEFAZ);<\/del><\/p>\n<p><del>c) Certid\u00e3o Negativa de D\u00e9bitos (Secretaria Municipal da Fazenda).<\/del><\/p>\n<p><del>VIII &#8211; prova de regularidade relativa ao Fundo de Garantia por Tempo de Servi\u00e7o (FGTS), demonstrando situa\u00e7\u00e3o regular no cumprimento dos encargos sociais institu\u00eddos por lei;<\/del><\/p>\n<p><del>IX &#8211; prova de inexist\u00eancia de d\u00e9bitos inadimplidos perante a Justi\u00e7a do Trabalho, mediante a apresenta\u00e7\u00e3o de certid\u00e3o negativa;<\/del><\/p>\n<p><del>X &#8211; autoriza\u00e7\u00e3o de funcionamento expedida pelo \u00f3rg\u00e3o regulador e fiscalizador, nos casos de esp\u00e9cie que obrigatoriamente necessitem de autoriza\u00e7\u00e3o;<\/del><\/p>\n<p><del>XI &#8211; declara\u00e7\u00e3o de que a empresa n\u00e3o emprega menor de 18 anos em trabalho noturno, perigoso ou insalubre, nem menor de 16 anos em quaisquer de suas atividades (art. 7\u00ba, XXXIII, da Constitui\u00e7\u00e3o);<\/del><\/p>\n<p><del>XII &#8211; declara\u00e7\u00e3o de que a empresa n\u00e3o est\u00e1 impedida de contratar com a Administra\u00e7\u00e3o P\u00fablica direta e indireta;<\/del><\/p>\n<p><del>XIII &#8211; declara\u00e7\u00e3o de que a empresa n\u00e3o foi declarada inid\u00f4nea pelo Poder P\u00fablico de nenhuma esfera;<\/del><\/p>\n<p><del>XIV &#8211; Certid\u00e3o Negativa de Primeira Inst\u00e2ncia &#8211; Natureza de Recupera\u00e7\u00e3o Judicial e Extrajudicial (Fal\u00eancia e Concordata) ou de execu\u00e7\u00e3o patrimonial, expedida no domic\u00edlio da matriz da pessoa jur\u00eddica;<\/del><\/p>\n<p><del>XV &#8211; outros documentos que a lei exigir.<\/del><\/p>\n<p><del>\u00a71\u00ba N\u00e3o poder\u00e3o ser credenciadas institui\u00e7\u00f5es com restri\u00e7\u00f5es encontradas a partir de consulta aos seguintes cadastros oficiais:<\/del><\/p>\n<p><del>a) Cadastro Nacional de Condenados por Ato de Improbidade Administrativa e por Ato que implique Inelegibilidade &#8211; CNCIAI (CNJ);<\/del><br \/>\n<del><a href=\"http:\/\/www.cnj.jus.br\/improbidade_adm\/consultar_requerido.php\">http:\/\/www.cnj.jus.br\/improbidade_adm\/consultar_requerido.php<\/a><\/del><\/p>\n<p><del>b) Cadastro Nacional de Empresas Inid\u00f4neas e Suspensas &#8211; CEIS (Minist\u00e9rio da Transpar\u00eancia, Fiscaliza\u00e7\u00e3o e Controladoria-Geral da Uni\u00e3o);<\/del><br \/>\n<del><a href=\"http:\/\/www.portaltransparencia.gov.br\/sancoes\/ceis?ordenarPor=nome&amp;direcao=asc\">http:\/\/www.portaltransparencia.gov.br\/sancoes\/ceis?ordenarPor=nome&amp;direcao=asc<\/a><\/del><\/p>\n<p><del>c) Cadastro de Inid\u00f4neos do TCU<\/del><br \/>\n<del><a href=\"https:\/\/contas.tcu.gov.br\/ords\/f?p=1660\">https:\/\/contas.tcu.gov.br\/ords\/f?p=1660<\/a>:3:34267031866041::::P3_TIPO_RELACAO:INIDONEO<\/del><\/p>\n<p><del>\u00a72\u00ba Deve ser apresentada c\u00f3pia autenticada dos documentos constantes dos incisos II, III, IV, V (quanto ao &#8220;ato de registro ou autoriza\u00e7\u00e3o para funcionamento&#8221;) e X, e os originais das declara\u00e7\u00f5es indicadas nos incisos XI, XII e XIII;<\/del><\/p>\n<p><del>\u00a73\u00ba Fica o Secret\u00e1rio Geral autorizado a expedir atos exigindo novos documentos, sempre que necess\u00e1rio;<\/del><\/p>\n<p><del>\u00a74\u00ba Compete \u00e0 Coordenadoria de Pagamento de Pessoal, no m\u00eas de mar\u00e7o de cada ano, solicitar e conferir os documentos de credenciamento, exceto para as que j\u00e1 os apresentaram no ano corrente.<\/del><\/p>\n<p><del>\u00a75\u00ba As institui\u00e7\u00f5es dever\u00e3o atender \u00e0s solicita\u00e7\u00f5es do \u00a74\u00ba no prazo de 15 (quinze) dias, sob pena de aplica\u00e7\u00e3o das san\u00e7\u00f5es do art. 24 desta Resolu\u00e7\u00e3o.<\/del><\/p>\n<p><del>\u00a76\u00ba Recebido pela Coordenadoria de Pagamento de Pessoal o pedido de credenciamento com a documenta\u00e7\u00e3o prevista neste artigo, cabe \u00e0 unidade indicar servidores titular e substituto que atuar\u00e3o como gestores ou fiscais do contrato de credenciamento que vier a ser celebrado, e encaminhar o processo \u00e0 Coordenadoria de Compras, Licita\u00e7\u00e3o e Contratos.<\/del><\/p>\n<p><del>\u00a77\u00ba A Coordenadoria de Compras, Licita\u00e7\u00e3o e Contratos dever\u00e1 manifestar-se sobre a habilita\u00e7\u00e3o ou n\u00e3o da institui\u00e7\u00e3o interessada, devendo juntar aos autos, no caso da primeira habilita\u00e7\u00e3o, minuta preenchida do contrato padr\u00e3o de credenciamento, aprovado pela Assessoria Jur\u00eddica da Presid\u00eancia, anexo a esta Resolu\u00e7\u00e3o, antes de encaminhar \u00e0 delibera\u00e7\u00e3o da Secretaria Geral.<\/del><\/p>\n<p><del>\u00a78\u00ba Devidamente instru\u00eddo o processo com as informa\u00e7\u00f5es decorrentes da Coordenadoria de Pagamento de Pessoal e da Coordenadoria de Compras, Licita\u00e7\u00e3o e Contratos, os autos seguem \u00e0 Secretaria Geral para confer\u00eancia e, no caso da primeira habilita\u00e7\u00e3o, assinatura das vias do contrato em nome do Poder Judici\u00e1rio do Estado do Esp\u00edrito Santo consignante.<\/del><\/p>\n<p><del>\u00a79\u00ba Assinado o contrato pelo Secret\u00e1rio Geral, os autos v\u00e3o \u00e0 Se\u00e7\u00e3o de Controle de Contratos e Conv\u00eanios (da Secretaria de Finan\u00e7as e Execu\u00e7\u00e3o Or\u00e7ament\u00e1ria), para colheita da assinatura da parte da institui\u00e7\u00e3o interessada, antes do envio para a Se\u00e7\u00e3o de Contrata\u00e7\u00e3o (Coordenadoria de Compras, Licita\u00e7\u00e3o e Contratos) disponibilizar o resumo no e-di\u00e1rio (Di\u00e1rio da Justi\u00e7a Eletr\u00f4nico).<\/del><\/p>\n<p><del>\u00a710 Disponibilizado o resumo do contrato de credenciamento no e-di\u00e1rio (Di\u00e1rio da Justi\u00e7a Eletr\u00f4nico), os autos ser\u00e3o movimentados para a Secretaria Geral, que ir\u00e1 conferir a indica\u00e7\u00e3o de servidores para a gest\u00e3o ou fiscaliza\u00e7\u00e3o do contrato, e disponibilizar o referido ato de designa\u00e7\u00e3o no e-di\u00e1rio (Di\u00e1rio da Justi\u00e7a Eletr\u00f4nico).<\/del><\/p>\n<p><del>\u00a711 Disponibilizado no e-di\u00e1rio (Di\u00e1rio da Justi\u00e7a Eletr\u00f4nico) o ato a que se refere o par\u00e1grafo anterior, o processo \u00e9 devolvido \u00e0 Coordenadoria de Pagamento de Pessoal para prestar a informa\u00e7\u00e3o relativa \u00e0 publica\u00e7\u00e3o no Portal da Transpar\u00eancia e manter o processo sob sua gest\u00e3o durante a execu\u00e7\u00e3o do contrato.<\/del><\/p>\n<p><del>Art. 14. A margem consign\u00e1vel prevista no art. 10 desta Resolu\u00e7\u00e3o ser\u00e1 informada por meio do Sistema Digital de Consigna\u00e7\u00f5es.<\/del><\/p>\n<p><del>Art. 15. Ficam autorizadas as averba\u00e7\u00f5es em folha de pagamento das consigna\u00e7\u00f5es provenientes da negocia\u00e7\u00e3o de contrato, referentes aos empr\u00e9stimos financeiros anteriores, quando devidamente autorizado pelo consignado.<\/del><\/p>\n<p><del>Art. 16. As consignat\u00e1rias ter\u00e3o o prazo m\u00e1ximo de 02 (dois) dias \u00fateis para informar ao consignado ou \u00e0s institui\u00e7\u00f5es financeiras, por ele autorizado, o saldo devedor do respectivo empr\u00e9stimo, sendo que essa informa\u00e7\u00e3o obrigatoriamente dever\u00e1 ser disponibilizada no Sistema Digital de Consigna\u00e7\u00f5es.<\/del><\/p>\n<p><del>\u00a71\u00ba O saldo devedor informado pelo detentor do contrato dever\u00e1 conter todos os dados para sua liquida\u00e7\u00e3o pela nova detentora do contrato, ag\u00eancia e conta para cr\u00e9dito, n\u00famero da Autoriza\u00e7\u00e3o para Desconto de Empr\u00e9stimo (ADE) e outras informa\u00e7\u00f5es que se fizerem necess\u00e1rias, bem como os valores discriminados para os pr\u00f3ximos 03 (tr\u00eas) dias, com redu\u00e7\u00e3o proporcional aos juros, conforme regulamenta\u00e7\u00e3o do Banco Central &#8211; BACEN.<\/del><\/p>\n<p><del>\u00a72\u00ba O pedido do saldo devedor de empr\u00e9stimos ter\u00e1 de ser registrado no Sistema Digital de Consigna\u00e7\u00f5es.<\/del><\/p>\n<p><del>\u00a73\u00ba Quando da liquida\u00e7\u00e3o do contrato, a informa\u00e7\u00e3o tamb\u00e9m dever\u00e1 ser registrada no Sistema Digital de Consigna\u00e7\u00f5es.<\/del><\/p>\n<p><del>\u00a74\u00ba O saldo devedor, quando requerido e n\u00e3o informado no prazo constante no caput deste artigo, autoriza o bloqueio tempor\u00e1rio do credenciamento para operar com novas consigna\u00e7\u00f5es, at\u00e9 que a informa\u00e7\u00e3o seja prestada.<\/del><\/p>\n<p><del>Art. 17. Quando informado o saldo devedor e caso ocorra a negocia\u00e7\u00e3o do contrato, a institui\u00e7\u00e3o compradora ter\u00e1 prazo de 03 (tr\u00eas) dias \u00fateis para depositar, na conta informada pela institui\u00e7\u00e3o vendedora, o valor da respectiva transa\u00e7\u00e3o.<\/del><\/p>\n<p><del>\u00a71\u00ba Ap\u00f3s a confirma\u00e7\u00e3o do valor da respectiva transa\u00e7\u00e3o, a institui\u00e7\u00e3o compradora dever\u00e1 efetuar o cr\u00e9dito \u00e0 vendedora, no valor informado por esta.<\/del><\/p>\n<p><del>\u00a72\u00ba A consignat\u00e1ria que teve o contrato de empr\u00e9stimo pessoal comprado fica obrigada a efetuar a liquida\u00e7\u00e3o do Contrato no Sistema Digital de Consigna\u00e7\u00f5es, no prazo m\u00e1ximo de 03 (tr\u00eas) dias \u00fateis, a partir da data em que ocorreu o registro do pagamento do saldo devedor do contrato, sob pena de bloqueio tempor\u00e1rio (art. 24, inciso I).<\/del><\/p>\n<p><del>\u00a73\u00ba O valor e o prazo da opera\u00e7\u00e3o na institui\u00e7\u00e3o proponente n\u00e3o podem ser superiores ao saldo devedor e ao prazo remanescente da opera\u00e7\u00e3o de cr\u00e9dito objeto da portabilidade na data da transfer\u00eancia de recursos.<\/del><\/p>\n<p><del>Art. 18. A consignat\u00e1ria fica obrigada a efetuar a liquida\u00e7\u00e3o de Contrato no Sistema Digital de Consigna\u00e7\u00f5es, quando de sua ocorr\u00eancia, no prazo m\u00e1ximo de 03 (tr\u00eas) dias \u00fateis, a partir da data da efetiva liquida\u00e7\u00e3o da opera\u00e7\u00e3o banc\u00e1ria, sob pena de bloqueio tempor\u00e1rio (art. 24, inciso I).<\/del><\/p>\n<p><del>Art. 19. O registro das consigna\u00e7\u00f5es facultativas no Sistema Digital de Consigna\u00e7\u00f5es somente ser\u00e1 permitido ap\u00f3s assinatura de documento pr\u00f3prio pelo consignado, no qual esteja expressa a autoriza\u00e7\u00e3o para desconto em folha de pagamento, o Custo Efetivo Total (CET), o n\u00famero de parcelas e os valores contratados, ou atrav\u00e9s de processo automatizado, via canais da institui\u00e7\u00e3o consignat\u00e1ria (como Terminais de autoatendimento, Internet e aplicativos de celular).<\/del><\/p>\n<p><del>\u00a71\u00ba Fica sob a responsabilidade da consignat\u00e1ria, na condi\u00e7\u00e3o de deposit\u00e1ria fiel, a guarda do documento mencionado no caput deste artigo, pelo prazo de 05 (cinco) anos, ap\u00f3s o t\u00e9rmino do contrato.<\/del><\/p>\n<p><del>\u00a72\u00ba O documento mencionado no caput deste artigo deve ser apresentado \u00e0 Coordenadoria de Pagamento de Pessoal, sempre que requisitado, no prazo de at\u00e9 03 (tr\u00eas) dias \u00fateis, contados a partir da notifica\u00e7\u00e3o.<\/del><\/p>\n<p><del>Art. 20. As consignat\u00e1rias dever\u00e3o ressarcir as despesas com processamento da consigna\u00e7\u00e3o em folha de pagamento.<\/del><\/p>\n<p><del>\u00a71\u00ba Est\u00e3o isentos do ressarcimento previsto no caput deste artigo: sindicatos, associa\u00e7\u00e3o de classe representativa de magistrados e\/ou servidores do Poder Judici\u00e1rio, mesmo que n\u00e3o exclusiva, e cooperativas de magistrados e\/ou servidores do Poder Judici\u00e1rio, que se enquadrem conforme defini\u00e7\u00e3o estabelecida no Art 1\u00ba, XI e que possuam consigna\u00e7\u00e3o conforme definido no Art 4\u00ba.<\/del><\/p>\n<p><del>\u00a72\u00ba O ressarcimento ao er\u00e1rio mencionado no caput deste artigo corresponder\u00e1 a 0,15% (quinze cent\u00e9simos por cento) do valor total do desconto mensal consignado na folha de pagamento de servidores e magistrados.<\/del><\/p>\n<p><del>\u00a73\u00ba O valor do ressarcimento mensal previsto no par\u00e1grafo anterior ser\u00e1 descontado do cr\u00e9dito a repassar \u00e0s consignat\u00e1rias pela \u00e1rea competente a partir do c\u00e1lculo realizado em folha de pagamento.<\/del><\/p>\n<p><del>Art. 21. A consigna\u00e7\u00e3o em folha de pagamento n\u00e3o implicar\u00e1 corresponsabilidade do Poder Judici\u00e1rio do Estado do Esp\u00edrito Santo (consignante) pelos compromissos assumidos pelos consignados junto \u00e0s consignat\u00e1rias.<\/del><\/p>\n<p><del>Art. 22. Havendo desconto n\u00e3o autorizado pelo consignado, a consignat\u00e1ria ficar\u00e1 respons\u00e1vel pelo imediato ressarcimento, n\u00e3o podendo exceder a 48 (quarenta e oito) horas.<\/del><\/p>\n<p><del>\u00a71\u00ba N\u00e3o havendo o ressarcimento na forma do caput deste artigo, o valor ser\u00e1 retido no momento de repasse dos valores referentes \u00e0s demais consigna\u00e7\u00f5es devidas \u00e0 consignat\u00e1ria e creditado ao consignado.<\/del><\/p>\n<p><del>\u00a72\u00ba Decorrido o prazo mencionado no caput deste artigo e n\u00e3o havendo o ressarcimento a consignat\u00e1ria ser\u00e1 suspensa.<\/del><\/p>\n<p><del>\u00a73\u00ba O ressarcimento previsto no caput e no \u00a71\u00ba e a suspens\u00e3o mencionada no \u00a72\u00ba deste artigo n\u00e3o isentam a consignat\u00e1ria da aplica\u00e7\u00e3o de outras penalidades previstas nesta Resolu\u00e7\u00e3o.<\/del><\/p>\n<p><del>Art. 23. Fica proibida a cess\u00e3o, transfer\u00eancia, venda ou aluguel do credenciamento para operar com consigna\u00e7\u00e3o em folha de pagamento, prevista nesta Resolu\u00e7\u00e3o.<\/del><\/p>\n<p><del>\u00a71\u00ba Fica proibida a cess\u00e3o, transfer\u00eancia, venda ou aluguel de dados de consignados por parte das consignat\u00e1rias e\/ou seus agentes, devendo os mesmos se sujeitar \u00e0 Lei N\u00ba 13.709, de 14 de agosto de 2018 (Lei Geral de Prote\u00e7\u00e3o de Dados).<\/del><\/p>\n<p><del>\u00a72\u00ba A consignat\u00e1ria que transgredir as proibi\u00e7\u00f5es contidas neste artigo sofrer\u00e1 a san\u00e7\u00e3o prevista no inciso II do art. 24, al\u00e9m das san\u00e7\u00f5es penais cab\u00edveis.<\/del><\/p>\n<p><del>Art. 24. O descumprimento de obriga\u00e7\u00f5es previstas nesta Resolu\u00e7\u00e3o ou em instru\u00e7\u00f5es expedidas pelos gestores de folhas de pagamento poder\u00e1 culminar, sem preju\u00edzo de outras previstas em lei, nas seguintes san\u00e7\u00f5es, aplicadas pelo Secret\u00e1rio Geral:<\/del><\/p>\n<p><del>I &#8211; bloqueio tempor\u00e1rio;<\/del><\/p>\n<p><del>II &#8211; descredenciamento.<\/del><\/p>\n<p><del>\u00a71\u00ba O bloqueio tempor\u00e1rio ser\u00e1 aplicado por prazo determinado, n\u00e3o inferior ao per\u00edodo de uma folha de pagamento, e impedir\u00e1 o processamento de novas consigna\u00e7\u00f5es at\u00e9 que seja regularizada a situa\u00e7\u00e3o que ensejou sua aplica\u00e7\u00e3o, ressalvada a hip\u00f3tese prevista no Art. 18, cujo prazo ser\u00e1 o necess\u00e1rio para a regulariza\u00e7\u00e3o da pend\u00eancia.<\/del><\/p>\n<p><del>\u00a72\u00ba A consignat\u00e1ria ser\u00e1 descredenciada quando n\u00e3o promover, em at\u00e9 180 (cento e oitenta) dias, a regulariza\u00e7\u00e3o da situa\u00e7\u00e3o que ensejou sua desativa\u00e7\u00e3o tempor\u00e1ria, ou quando houver prestado declara\u00e7\u00e3o falsa com finalidade de criar obriga\u00e7\u00e3o ou alterado a verdade sobre fato juridicamente relevante.<\/del><\/p>\n<p><del>I &#8211; o descredenciamento impedir\u00e1 o processamento de qualquer opera\u00e7\u00e3o de consigna\u00e7\u00e3o, ressalvados os contratos j\u00e1 em andamento.<\/del><\/p>\n<p><del>II &#8211; a consignat\u00e1ria descredenciada ficar\u00e1 impedida de solicitar novo credenciamento e firmar novo contrato com o respons\u00e1vel pela operacionaliza\u00e7\u00e3o das consigna\u00e7\u00f5es por um per\u00edodo de:<\/del><\/p>\n<p><del>a) um ano, na hip\u00f3tese de n\u00e3o regulariza\u00e7\u00e3o no prazo de 180 dias (\u00a72\u00ba, primeira parte);<\/del><\/p>\n<p><del>b) cinco anos, na hip\u00f3tese de falsidade (\u00a72\u00ba, parte final).<\/del><\/p>\n<p><del>\u00a73\u00ba As penalidades a serem aplicadas em desfavor das consignat\u00e1rias n\u00e3o afetar\u00e3o as consigna\u00e7\u00f5es j\u00e1 contratadas e que estejam de acordo com o que preceitua esta Resolu\u00e7\u00e3o, que continuar\u00e3o a ser descontadas em folha de pagamento at\u00e9 sua integral liquida\u00e7\u00e3o.<\/del><\/p>\n<p><del>Art. 25. As consignat\u00e1rias ficam obrigadas a promover no Sistema Digital de Consigna\u00e7\u00f5es os registros e as atualiza\u00e7\u00f5es do Custo Efetivo Total &#8211; CET, calculado conforme regulamenta\u00e7\u00e3o do Banco Central do Brasil.<\/del><\/p>\n<p><del>\u00a71\u00ba A vig\u00eancia do CET de empr\u00e9stimos ter\u00e1 efeito a partir do 1\u00ba dia \u00fatil ap\u00f3s a data do registro efetuado no Sistema Digital de Consigna\u00e7\u00f5es.<\/del><\/p>\n<p><del>\u00a72\u00ba Em hip\u00f3tese alguma ser\u00e1 permitido registro de contrato de empr\u00e9stimo com valor de CET superior ao publicado pela consignat\u00e1ria no Sistema Digital de Consigna\u00e7\u00f5es.<\/del><\/p>\n<p><del>Art. 26. As taxas m\u00e1ximas de juros, nos casos de empr\u00e9stimos consignados, obedecer\u00e3o \u00e0quelas fixadas para os servidores da Administra\u00e7\u00e3o P\u00fablica Federal, nos termos do art. 4\u00ba, \u00a73\u00ba, II, do Decreto Federal n\u00ba 8.690\/2016.<\/del><\/p>\n<p><del>Art. 27. As reclama\u00e7\u00f5es referentes ao n\u00e3o cumprimento das normas estabelecidas ou reclama\u00e7\u00f5es prestadas por consignados, dever\u00e3o ser encaminhadas ao Secret\u00e1rio Geral, por escrito, devidamente fundamentadas, garantindo-se sempre o amplo direito de defesa.<\/del><\/p>\n<p><del>Art. 28. A Secretaria Geral editar\u00e1 atos complementares, necess\u00e1rios ao fiel cumprimento desta Resolu\u00e7\u00e3o.<\/del><\/p>\n<p><del>Par\u00e1grafo \u00fanico. O disposto no caput deste artigo poder\u00e1 ser delegado.<\/del><\/p>\n<p><del>Art. 29. Ficam os gestores de folha de pagamento autorizados, no \u00e2mbito de suas atribui\u00e7\u00f5es, a expedir instru\u00e7\u00f5es necess\u00e1rias \u00e0 execu\u00e7\u00e3o de procedimentos para inser\u00e7\u00e3o de consigna\u00e7\u00f5es em folha de pagamento.<\/del><\/p>\n<p><del>Art. 30. Ficam revogadas a Resolu\u00e7\u00e3o TJES n\u00ba 29\/2018, disponibilizada no e-di\u00e1rio (Di\u00e1rio da Justi\u00e7a Eletr\u00f4nico) de 29.08.2018, e as demais disposi\u00e7\u00f5es em contr\u00e1rio.<\/del><\/p>\n<p><del>Art. 31. Os casos omissos e as d\u00favidas que surjam poder\u00e3o ser levados \u00e0 considera\u00e7\u00e3o da Assessoria Jur\u00eddica da Presid\u00eancia.<\/del><\/p>\n<p><del>Art. 32. Esta Resolu\u00e7\u00e3o entra em vigor na data de sua publica\u00e7\u00e3o, concedendo \u00e0s \u00e1reas respons\u00e1veis pelas altera\u00e7\u00f5es de procedimentos e sistemas de inform\u00e1tica o prazo de 60 (sessenta) dias para ajustes, com reflexo na folha de pagamento subsequente ao t\u00e9rmino dos ajustes necess\u00e1rios.<\/del><\/p>\n<p><del>Publique-se.<\/del><\/p>\n<p><del>Vit\u00f3ria (ES), 22 de abril de 2021.<\/del><\/p>\n<p style=\"text-align: center;\"><del><strong>Des. RONALDO GON\u00c7ALVES DE SOUSA<\/strong><\/del><br \/>\n<del>Presidente<\/del><\/p>\n<p style=\"text-align: center;\"><del>republicado por incorre\u00e7\u00f5es<\/del><\/p>\n<p style=\"text-align: center;\"><del><strong><a href=\"https:\/\/sistemas.tjes.jus.br\/ediario\/images\/ANEXO_DA_RESOLU%C3%87%C3%83O_N%C2%BA_008.pdf\">ANEXO CLIQUE AQUI<\/a><\/strong><\/del><\/p>\n","protected":false},"excerpt":{"rendered":"<p>REVOGADO PELA RESOLU\u00c7\u00c3O 066\/2024 DISP. 13\/05\/2024 PODER JUDICI\u00c1RIO DO ESTADO DO ESP\u00cdRITO SANTO &#8211; PJES RUA DESEMBARGADOR HOMERO MAFRA,60 &#8211; Bairro ENSEADA DO SU\u00c1 &#8211; CEP 29050906 &#8211; Vit\u00f3ria &#8211; ES &#8211; www.tjes.jus.br RESOLU\u00c7\u00c3O N\u00ba 008\/2021 \u00a0 Regulamenta o procedimento de consigna\u00e7\u00e3o em folha de pagamento\u00a0no \u00e2mbito do Poder Judici\u00e1rio do Estado do Esp\u00edrito Santo. [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,13],"tags":[],"_links":{"self":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/31599"}],"collection":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/comments?post=31599"}],"version-history":[{"count":4,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/31599\/revisions"}],"predecessor-version":[{"id":40050,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/31599\/revisions\/40050"}],"wp:attachment":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/media?parent=31599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/categories?post=31599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/tags?post=31599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}