{"id":31851,"date":"2021-05-17T14:57:22","date_gmt":"2021-05-17T17:57:22","guid":{"rendered":"https:\/\/www.tjes.jus.br\/corregedoria\/?p=31851"},"modified":"2021-07-19T14:11:16","modified_gmt":"2021-07-19T17:11:16","slug":"ato-normativo-no-037-2021-disp-17-05-2021","status":"publish","type":"post","link":"https:\/\/www.tjes.jus.br\/corregedoria\/2021\/05\/17\/ato-normativo-no-037-2021-disp-17-05-2021\/","title":{"rendered":"ATO NORMATIVO N\u00ba 038\/2021 \u2013 DISP. 17\/05\/2021 &#8211; ALTERADO"},"content":{"rendered":"<h2 align=\"center\"><span style=\"color: #ff0000;\">Alterado pelo<\/span>\u00a0<a href=\"https:\/\/www.tjes.jus.br\/corregedoria\/2021\/07\/16\/ato-normativo-no-55-2021\/\">ATO NORMATIVO N\u00ba 55\/2021<\/a> <span style=\"color: #ff0000;\">disp. em 16\/07\/2021<\/span><\/h2>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong>PODER JUDICI\u00c1RIO DO ESTADO DO ESP\u00cdRITO SANTO &#8211; PJES<\/strong><\/p>\n<p style=\"text-align: center;\">RUA DESEMBARGADOR HOMERO MAFRA,60 &#8211; Bairro ENSEADA DO SU\u00c1 &#8211; CEP 29050906 &#8211; Vit\u00f3ria &#8211; ES &#8211; www.tjes.jus.br<\/p>\n<p style=\"text-align: center;\"><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong>ATO NORMATIVO N\u00ba\u00a0 038 \/2021<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Disciplina o retorno ao\u00a0trabalho presencial dos servidores do\u00a0Poder Judicia\u0301rio do Estado do Esp\u00edrito Santo imunizados com a vacina contra a COVID-19.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">O EXCELENT\u00cdSSIMO SENHOR DESEMBARGADOR\u00a0<strong>RONALDO GONC\u0327ALVES DE SOUSA<\/strong>, PRESIDENTE DO E. TRIBUNAL DE JUSTI\u00c7A DO ESTADO DO ESP\u00cdRITO SANTO, no uso de suas atribuic\u0327o\u0303es legais e,<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">CONSIDERANDO o <a href=\"https:\/\/www.tjes.jus.br\/corregedoria\/2020\/08\/07\/ato-normativo-no-088-2020-disp-07-08-2020\/\">Ato Normativo n\u00ba 088\/2020<\/a> que, disciplina o retorno gradual do trabalho presencial do Poder Judici\u00e1rio do Estado do Esp\u00edrito Santo;<\/p>\n<p style=\"text-align: justify;\">CONSIDERANDO o <a href=\"https:\/\/www.tjes.jus.br\/corregedoria\/2021\/05\/03\/ato-normativo-no-036-2021-disp-03-05-2021\/\">Ato Normativo n\u00ba 036\/2021<\/a>\u00a0que,\u00a0determina que a partir de 10\/05\/2021 o Poder Judici\u00e1rio do Estado do Esp\u00edrito Santo progrida para a fase final prevista no o <a href=\"https:\/\/www.tjes.jus.br\/corregedoria\/2020\/08\/07\/ato-normativo-no-088-2020-disp-07-08-2020\/\">Ato Normativo n\u00ba 088\/2020<\/a> do TJES;<\/p>\n<p style=\"text-align: justify;\">CONSIDERANDO que\u00a0a pandemia causada pelo novo coronavi\u0301rus (Covid-19) e declarada pela Organizac\u0327a\u0303o Mundial de Sau\u0301de (OMS) persiste;<\/p>\n<p style=\"text-align: justify;\">CONSIDERANDO os termos da Portaria n\u00ba 092-R, de 06\u00a0de maio de 2021, da Secretaria de Estado da Sa\u00fade do Esp\u00edrito Santo;<\/p>\n<p style=\"text-align: justify;\">RESOLVE:<\/p>\n<p style=\"text-align: justify;\">Art.1\u00ba\u00a0 Determinar que os servidores do Poder Judici\u00e1rio do Estado do Esp\u00edrito Santo, imunizados com a VACINA CONTRA A COVID-19 retornem ao trabalho presencial.<\/p>\n<p style=\"text-align: justify;\">\u00a7 1\u00ba O retorno ao trabalho presencial dever\u00e1 ocorrer de acordo com a data da vacina contra a COVID-19 de acordo com os per\u00edodos especificados a seguir:<\/p>\n<p style=\"text-align: justify;\">I- Vacina COVISHIELD (Oxford\/Fiocruz): 28 dias ap\u00f3s a aplica\u00e7\u00e3o da primeira dose.<\/p>\n<p style=\"text-align: justify;\">II- Vacina CORONAVAC (Sinovac\/Butantan): 14 dias ap\u00f3s a aplica\u00e7\u00e3o da segunda dose.<\/p>\n<p class=\"m_Texto_Justificado_Recuo_Primeira_Linha\" style=\"text-align: justify;\">III &#8211; Vacina PFIZER (BioNTech): 28 dias ap\u00f3s a aplica\u00e7\u00e3o da primeira dose.\u00a0<strong>(Inclu\u00eddo pelo <a href=\"https:\/\/www.tjes.jus.br\/corregedoria\/2021\/07\/16\/ato-normativo-no-55-2021\/\">Ato Normativo n\u00ba\u00a055\/2021<\/a>, disponibilizado em 16\/07\/2021)<\/strong><b><\/b><\/p>\n<p class=\"m_Texto_Justificado_Recuo_Primeira_Linha\" style=\"text-align: justify;\">IV- Vacina JANSSEN (Johnson &amp; Jonhson): 28 dias ap\u00f3s a aplica\u00e7\u00e3o da dose \u00fanica\u00a0<strong>(Inclu\u00eddo pelo <a href=\"https:\/\/www.tjes.jus.br\/corregedoria\/2021\/07\/16\/ato-normativo-no-55-2021\/\">Ato Normativo n\u00ba\u00a055\/2021<\/a>, disponibilizado em 16\/07\/2021)<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a72\u00ba\u00a0Os servidores que j\u00e1 tiverem sido imunizados e cumprido os prazos previstos no \u00a71\u00ba deste artigo dever\u00e3o retornar \u00e0s suas atividades presenciais no dia 17\u00a0de maio de 2021 (segunda-feira), e em caso de n\u00e3o comparecimento passar\u00e1 a contar falta a partir desta data.<\/p>\n<p style=\"text-align: justify;\">Art. 2\u00b0 O servidor com contraindica\u00e7\u00e3o m\u00e9dica para uso do imunizante contra a COVID-19 dever\u00e1 apresentar laudo m\u00e9dico\u00a0para garantir sua perman\u00eancia em regime de trabalho remoto.<\/p>\n<p style=\"text-align: justify;\">Art. 3\u00b0 O servidor a que se refere no caput do art. 1\u00ba dever\u00e1 apresentar \u00e0 chefia imediata o comprovante da imuniza\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Art. 4\u00b0\u00a0Fica a crite\u0301rio do gestor da unidade , quando poss\u00edvel, a realiza\u00e7\u00e3o\u00a0 do revezamento\u00a0 dos servidores para o exerc\u00edcio das\u00a0atividades presenciais nos setores administrativos e judiciais.<\/p>\n<p style=\"text-align: justify;\">\u00a7 1\u00ba.\u00a0O revezamento est\u00e1 autorizado desde que n\u00e3o importe em aumento de despesa ou \u00f4nus financeiro para o Poder Judici\u00e1rio.<\/p>\n<p style=\"text-align: justify;\">\u00a72\u00ba.\u00a0A quantidade de servidores e estagi\u00e1rios por per\u00edodo na mesma sala deve ser, no m\u00e1ximo, aquela que possibilite respeitar a dist\u00e2ncia de 1,5 metros entre as pessoas.<\/p>\n<p style=\"text-align: justify;\">Art. 5\u00ba\u00a0 As regras de biosseguran\u00e7a previstas no <a href=\"https:\/\/www.tjes.jus.br\/corregedoria\/2020\/08\/07\/ato-normativo-no-088-2020-disp-07-08-2020\/\">Ato Normativo n\u00ba 88\/2020<\/a> do TJES devem ser\u00a0rigorosamente observadas.<\/p>\n<p>Art. 6\u00ba. Este Ato Normativo entra em vigor no dia 17\/05\/2021.<\/p>\n<p>&nbsp;<\/p>\n<p>Publique-se. Registre-se. Cumpra-se.<\/p>\n<p>&nbsp;<\/p>\n<p>Vit\u00f3ria\/ES, 14\u00a0de maio\u00a0de 2021.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong>Desembargador RONALDO GON\u00c7ALVES DE SOUSA<\/strong><\/p>\n<p style=\"text-align: center;\">Presidente do Tribunal de Justi\u00e7a do Esp\u00edrito Santo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alterado pelo\u00a0ATO NORMATIVO N\u00ba 55\/2021 disp. em 16\/07\/2021 &nbsp; PODER JUDICI\u00c1RIO DO ESTADO DO ESP\u00cdRITO SANTO &#8211; PJES RUA DESEMBARGADOR HOMERO MAFRA,60 &#8211; Bairro ENSEADA DO SU\u00c1 &#8211; CEP 29050906 &#8211; Vit\u00f3ria &#8211; ES &#8211; www.tjes.jus.br \u00a0 &nbsp; ATO NORMATIVO N\u00ba\u00a0 038 \/2021 &nbsp; Disciplina o retorno ao\u00a0trabalho presencial dos servidores do\u00a0Poder Judicia\u0301rio do Estado [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,14],"tags":[],"_links":{"self":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/31851"}],"collection":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/comments?post=31851"}],"version-history":[{"count":7,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/31851\/revisions"}],"predecessor-version":[{"id":32283,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/31851\/revisions\/32283"}],"wp:attachment":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/media?parent=31851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/categories?post=31851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/tags?post=31851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}