{"id":36583,"date":"2023-04-26T15:14:05","date_gmt":"2023-04-26T18:14:05","guid":{"rendered":"https:\/\/www.tjes.jus.br\/corregedoria\/?p=36583"},"modified":"2023-04-26T15:33:39","modified_gmt":"2023-04-26T18:33:39","slug":"ato-normativo-no-203-2023-disp-26-04-2023","status":"publish","type":"post","link":"https:\/\/www.tjes.jus.br\/corregedoria\/2023\/04\/26\/ato-normativo-no-203-2023-disp-26-04-2023\/","title":{"rendered":"ATO NORMATIVO N\u00ba 203\/2023 \u2013 DISP. 26\/04\/2023"},"content":{"rendered":"<p style=\"text-align: center;\">PODER JUDICI\u00c1RIO DO ESTADO DO ESP\u00cdRITO SANTO &#8211; PJES<\/p>\n<p style=\"text-align: center;\">RUA DESEMBARGADOR HOMERO MAFRA,60 &#8211; Bairro ENSEADA DO SU\u00c1 &#8211; CEP 29050906 &#8211; Vit\u00f3ria &#8211; ES &#8211; www.tjes.jus.br<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong>ATO NORMATIVO N\u00ba\u00a0<\/strong><strong>203\u00a0<\/strong><strong>\/2023<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>O Presidente do Tribunal de Justi\u00e7a do Estado do Esp\u00edrito Santo, no uso de suas atribui\u00e7\u00f5es legais e regimentais,<\/p>\n<p>&nbsp;<\/p>\n<p>Considerando o teor do Processo SEI n\u00ba 7000004-30.2023.8.08.0060, inaugurado pelo MM. Juiz de Direito Diretor do Foro da Comarca de At\u00edlio Vivacqua\/ES,<\/p>\n<p>&nbsp;<\/p>\n<p>Considerando a manifesta\u00e7\u00e3o do Eminente Presidente do Comit\u00ea de Governan\u00e7a de Tecnologia da Informa\u00e7\u00e3o e Comunica\u00e7\u00e3o deste Egr\u00e9gio Tribunal de Justi\u00e7a,<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>RESOLVE:<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Art. 1\u00ba \u2013 Suspender, por 30 (trinta) dias, a contar de 11\/04\/2023, os prazos processuais com rela\u00e7\u00e3o aos processos f\u00edsicos de compet\u00eancia c\u00edvel que tramitam no sistema E-Jud da Vara \u00danica da Comarca de At\u00edlio Vivacqua\/ES, sem preju\u00edzo da realiza\u00e7\u00e3o das audi\u00eancias designadas, impulso processual e atendimento externo para as demandas de extrema urg\u00eancia, ressalvando-se os processos que n\u00e3o ser\u00e3o digitalizados, conforme o <a href=\"https:\/\/www.tjes.jus.br\/corregedoria\/2022\/04\/06\/ato-normativo-conjunto-no-007-2022-disp-06-04-2022-republicacao\/\">Ato Normativo Conjunto n\u00ba 007\/2022<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p>Publique-se.<\/p>\n<p>&nbsp;<\/p>\n<p>Vit\u00f3ria\/ES, 25 de abril de 2023.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong>Desembargador Fabio Clem de Oliveira<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Presidente<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PODER JUDICI\u00c1RIO DO ESTADO DO ESP\u00cdRITO SANTO &#8211; PJES RUA DESEMBARGADOR HOMERO MAFRA,60 &#8211; Bairro ENSEADA DO SU\u00c1 &#8211; CEP 29050906 &#8211; Vit\u00f3ria &#8211; ES &#8211; www.tjes.jus.br &nbsp; ATO NORMATIVO N\u00ba\u00a0203\u00a0\/2023 &nbsp; &nbsp; O Presidente do Tribunal de Justi\u00e7a do Estado do Esp\u00edrito Santo, no uso de suas atribui\u00e7\u00f5es legais e regimentais, &nbsp; Considerando o [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,14],"tags":[],"_links":{"self":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/36583"}],"collection":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/comments?post=36583"}],"version-history":[{"count":2,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/36583\/revisions"}],"predecessor-version":[{"id":36594,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/36583\/revisions\/36594"}],"wp:attachment":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/media?parent=36583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/categories?post=36583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/tags?post=36583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}