{"id":40882,"date":"2024-08-12T12:48:11","date_gmt":"2024-08-12T15:48:11","guid":{"rendered":"https:\/\/www.tjes.jus.br\/corregedoria\/?p=40882"},"modified":"2024-08-12T12:54:28","modified_gmt":"2024-08-12T15:54:28","slug":"oficio-circular-cgjes-2216677-2024-disp-12-08-2024","status":"publish","type":"post","link":"https:\/\/www.tjes.jus.br\/corregedoria\/2024\/08\/12\/oficio-circular-cgjes-2216677-2024-disp-12-08-2024\/","title":{"rendered":"OF\u00cdCIO CIRCULAR CGJES 2216677\/2024\u2013 DISP. 12\/08\/2024"},"content":{"rendered":"\n<p class=\"Texto_Centralizado\" style=\"text-align: center;\"><strong>PODER JUDICI\u00c1RIO DO ESTADO DO ESP\u00cdRITO SANTO &#8211; PJES<\/strong><\/p>\n<p class=\"Texto_Centralizado\" style=\"text-align: center;\"><strong>CORREGEDORIA GERAL DA\u00a0JUSTI\u00c7A<\/strong><\/p>\n<p class=\"Texto_Cabe\u00e7alho\" style=\"text-align: center;\">Av. Jo\u00e3o Batista Parra, n\u00ba\u00a0320, Enseada do Su\u00e1 &#8211; Vit\u00f3ria\/ES<br \/>CEP: 29.050-375 &#8211;\u00a0Telefone: (27) 3145-3100<br \/>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p class=\"Texto_Centralizado_Maiusculas\" style=\"text-align: center;\"><strong>OF\u00cdCIO CIRCULAR CGJES\u00a02216677\/7000286-20.2024.8.08.0000<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p class=\"Texto_Justificado\">De ordem do\u00a0Exmo. Sr. Desembargador Corregedor-Geral da Justi\u00e7a do Estado do Esp\u00edrito Santo, no uso de suas atribui\u00e7\u00f5es legais e,<\/p>\n<p>\u00a0<\/p>\n<p class=\"Texto_Justificado\"><strong>CONSIDERANDO<\/strong>\u00a0que a Corregedoria Geral da Justi\u00e7a \u00e9 \u00f3rg\u00e3o de fiscaliza\u00e7\u00e3o, disciplina e orienta\u00e7\u00e3o administrativa, com circunscri\u00e7\u00e3o em todo o Estado, conforme art. 35 da Lei Complementar Estadual n\u00ba 234\/2002 (COJES);<\/p>\n<p>\u00a0<\/p>\n<p class=\"Texto_Justificado\"><strong>CONSIDERANDO<\/strong>\u00a0o previsto no Art. 1\u00ba do Provimento n\u00ba 052\/2021, disponibilizado no Di\u00e1rio Eletr\u00f4nico da Justi\u00e7a do dia 07 de maio de 2021;<\/p>\n<p>\u00a0<\/p>\n<p class=\"Texto_Justificado\"><strong>CONSIDERANDO<\/strong>\u00a0o recebimento dos malotes digitais n\u00ba 824202411824765 e 819202412278628, referente aos Atos Ordin\u00e1rios n.\u00a00068044-95.2024.8.24.0710 e\u00a00039745-11.2024.8.24.0710 enviados pela Corregedoria-Geral da Justi\u00e7a do Estado de Santa Catarina;<\/p>\n<p class=\"Texto_Justificado\"><br \/><strong>CONSIDERANDO<\/strong>\u00a0que as referidas comunica\u00e7\u00f5es enviadas pela\u00a0Escrivania de Paz do Distrito de Campinas, e pelo\u00a0Cart\u00f3rio de 2\u00ba Of\u00edcio de Registro de Im\u00f3veis de Florian\u00f3polis\/SC informa poss\u00edveis falsifica\u00e7\u00f5es de documentos, conforme anexos.<\/p>\n<p class=\"Texto_Justificado\"><br \/><strong>CONSIDERANDO<\/strong>\u00a0que a referida Serventia j\u00e1 procedeu o registro da ocorr\u00eancia junto a Policia Civil do Estado de Santa Catarina, conforme Boletins de Ocorr\u00eancias em anexo.<\/p>\n<p class=\"Texto_Justificado\"><br \/><strong>RECOMENDO<\/strong>\u00a0aos Ju\u00edzes de Direito Diretores dos F\u00f3runs, Membros do Minist\u00e9rio P\u00fablico, Advogados, Not\u00e1rios e Registradores, Serventu\u00e1rios e a quem mais possa\u00a0interessar, que observem o comunicado em anexo, e adotem as provid\u00eancias que entenderem pertinentes.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p class=\"Texto_Justificado\"><br \/><strong>Publique-se. Cumpra-se.<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p class=\"Tabela_Texto_Centralizado\" style=\"text-align: center;\"><strong>MAGALI BARBOSA DE OLIVEIRA<\/strong><\/p>\n<p class=\"Tabela_Texto_Centralizado\" style=\"text-align: center;\"><strong>Coordenadora\u00a0de Monitoramento do Foro Judicial e Extrajudicial<\/strong><\/p>\n<p class=\"Tabela_Texto_Alinhado_Esquerda\" style=\"text-align: center;\">Vit\u00f3ria\/ES, 07 de agosto de 2024.<\/p>\n<p class=\"Texto_Centralizado\" style=\"text-align: center;\"><strong>Corregedor Geral da Justi\u00e7a<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p style=\"text-align: center;\"><strong><a href=\"https:\/\/sistemas.tjes.jus.br\/ediario\/images\/ATO_0039745-11.2024.8.24.0710_redacted_organized.pdf\">ANEXO I &#8211; CLIQUE AQUI<\/a><\/strong><\/p>\n<p>\u00a0<\/p>\n<p style=\"text-align: center;\"><strong><a href=\"https:\/\/sistemas.tjes.jus.br\/ediario\/images\/ATO_._0068044-95.2024.8.24.0710_organized.pdf\">ANEXO II &#8211; CLIQUE AQUI<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PODER JUDICI\u00c1RIO DO ESTADO DO ESP\u00cdRITO SANTO &#8211; PJES CORREGEDORIA GERAL DA\u00a0JUSTI\u00c7A Av. Jo\u00e3o Batista Parra, n\u00ba\u00a0320, Enseada do Su\u00e1 &#8211; Vit\u00f3ria\/ESCEP: 29.050-375 &#8211;\u00a0Telefone: (27) 3145-3100\u00a0 \u00a0 OF\u00cdCIO CIRCULAR CGJES\u00a02216677\/7000286-20.2024.8.08.0000 \u00a0 \u00a0 De ordem do\u00a0Exmo. Sr. Desembargador Corregedor-Geral da Justi\u00e7a do Estado do Esp\u00edrito Santo, no uso de suas atribui\u00e7\u00f5es legais e, \u00a0 CONSIDERANDO\u00a0que a [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/40882"}],"collection":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/comments?post=40882"}],"version-history":[{"count":3,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/40882\/revisions"}],"predecessor-version":[{"id":40886,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/40882\/revisions\/40886"}],"wp:attachment":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/media?parent=40882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/categories?post=40882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/tags?post=40882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}