{"id":9193,"date":"2016-12-02T17:44:19","date_gmt":"2016-12-02T19:44:19","guid":{"rendered":"https:\/\/www.tjes.jus.br\/corregedoria\/?p=9193"},"modified":"2016-12-02T17:44:19","modified_gmt":"2016-12-02T19:44:19","slug":"oficio-circular-no-1062013-publ-em-19022013","status":"publish","type":"post","link":"https:\/\/www.tjes.jus.br\/corregedoria\/2016\/12\/02\/oficio-circular-no-1062013-publ-em-19022013\/","title":{"rendered":"OF\u00cdCIO-CIRCULAR N\u00ba 106\/2013 &#8211; PUBL. EM 19\/02\/2013"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>ESTADO DO ESP\u00cdRITO SANTO<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>PODER JUDICI\u00c1RIO<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>CORREGEDORIA GERAL DA JUSTI\u00c7A<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>OF\u00cdCIO-CIRCULAR N\u00ba. 106\/2013<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>(Favor mencionar essa refer\u00eancia)<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Protocolo n\u00ba 201300127387<\/strong><\/p>\n<p style=\"text-align: justify;\">O Exmo. Sr. Desembargador Corregedor-Geral da Justi\u00e7a do Estado do Esp\u00edrito Santo, no uso de suas atribui\u00e7\u00f5es legais:<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong> o recebimento do Of\u00edcio Circular n\u00ba 019\/2013-SEC da lavra da Excelent\u00edssima Corregedora-Geral da Justi\u00e7a, Des. Nelma Branco Ferreira Perilo;<\/p>\n<p style=\"text-align: justify;\"><strong>CONSIDERANDO<\/strong> que referido Of\u00edcio-Circular informa sobre o DESAPARECIMENTO de 03 (tr\u00eas) vias, em branco, do formul\u00e1rio de Declara\u00e7\u00e3o de Nascido Vivo n\u00ba 30-63702976, das depend\u00eancias do Esquadr\u00e3o de Sa\u00fade da Base A\u00e9rea da unidade judici\u00e1ria de An\u00e1polis\/GO, ficando ad cautelum cancelada a sua validade;<\/p>\n<p style=\"text-align: justify;\"><strong>RECOMENDO<\/strong> aos Ju\u00edzes de Direito Diretores dos F\u00f3runs, Membros do Minist\u00e9rio P\u00fablico, Advogados, Not\u00e1rios e Registradores dos Cart\u00f3rios de Registro Civil, Serventu\u00e1rios e a quem mais possa interessar, que observem o Of\u00edcio-Circular supra citado, e adotem as provid\u00eancias que entenderem pertinentes.<\/p>\n<p style=\"text-align: justify;\"><strong>Publique-se.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Cumpra-se.<\/strong><\/p>\n<p style=\"text-align: justify;\">Vit\u00f3ria\/ES, 15 de fevereiro de 2013.<\/p>\n<p style=\"text-align: center;\"><strong>DES. CARLOS HENRIQUE RIOS DO AMARAL<br \/>\nCorregedor-Geral da Justi\u00e7a<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ESTADO DO ESP\u00cdRITO SANTO PODER JUDICI\u00c1RIO CORREGEDORIA GERAL DA JUSTI\u00c7A OF\u00cdCIO-CIRCULAR N\u00ba. 106\/2013 (Favor mencionar essa refer\u00eancia) Protocolo n\u00ba 201300127387 O Exmo. Sr. Desembargador Corregedor-Geral da Justi\u00e7a do Estado do Esp\u00edrito Santo, no uso de suas atribui\u00e7\u00f5es legais: CONSIDERANDO o recebimento do Of\u00edcio Circular n\u00ba 019\/2013-SEC da lavra da Excelent\u00edssima Corregedora-Geral da Justi\u00e7a, Des. Nelma [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/9193"}],"collection":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/comments?post=9193"}],"version-history":[{"count":1,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/9193\/revisions"}],"predecessor-version":[{"id":9194,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/posts\/9193\/revisions\/9194"}],"wp:attachment":[{"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/media?parent=9193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/categories?post=9193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tjes.jus.br\/corregedoria\/wp-json\/wp\/v2\/tags?post=9193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}